{"id":13709,"date":"2026-03-17T09:09:13","date_gmt":"2026-03-17T08:09:13","guid":{"rendered":"https:\/\/vanfittery.de\/?page_id=13709"},"modified":"2026-04-01T16:28:38","modified_gmt":"2026-04-01T14:28:38","slug":"jobs","status":"publish","type":"page","link":"https:\/\/vanfittery.de\/fr\/jobs\/","title":{"rendered":"Emplois"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13709\" class=\"elementor elementor-13709\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eeef3fa gp e-flex e-con-boxed e-con e-parent\" data-id=\"eeef3fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8315928 gp elementor-widget elementor-widget-heading\" data-id=\"8315928\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Emplois - Rejoins l'\u00e9quipe !<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a184a5e gpt elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"a184a5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-579a102 e-con-full sw e-flex e-con e-child\" data-id=\"579a102\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c4970d elementor-widget elementor-widget-heading\" data-id=\"1c4970d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Employ\u00e9 dans la production \/ transformation du bois (m\/f) sur la base d'un mini-job<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dbc402 elementor-widget elementor-widget-text-editor\" data-id=\"6dbc402\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"14\"><b data-path-to-node=\"14\" data-index-in-node=\"0\">Emplacement :<\/b> Postau | <b data-path-to-node=\"14\" data-index-in-node=\"19\">Art :<\/b> Minijob (jusqu'\u00e0 603 \u20ac) | <b data-path-to-node=\"14\" data-index-in-node=\"46\">Salaire :<\/b> 15 - 20 \u20ac \/ heure<\/p><p data-path-to-node=\"15\"><b data-path-to-node=\"15\" data-index-in-node=\"0\">A propos du travail :<\/b> Tu as envie d'un travail manuel dans un environnement d\u00e9tendu ? Pour notre production \u00e0 Postau, nous recherchons d\u00e8s maintenant un soutien actif sur la base d'un mini-job. Il r\u00e8gne chez nous une atmosph\u00e8re de travail paisible et concentr\u00e9e - id\u00e9ale pour tous ceux qui aiment travailler de leurs mains et veulent voir un r\u00e9sultat tangible \u00e0 la fin de la journ\u00e9e.<\/p><p data-path-to-node=\"16\"><b data-path-to-node=\"16\" data-index-in-node=\"0\">Tes t\u00e2ches :<\/b><\/p><ul data-path-to-node=\"17\"><li><p data-path-to-node=\"17,0,0\">Activit\u00e9s manuelles et soutien g\u00e9n\u00e9ral \u00e0 la production<\/p><\/li><li><p data-path-to-node=\"17,1,0\">Travailler avec diff\u00e9rents mat\u00e9riaux en bois<\/p><\/li><li><p data-path-to-node=\"17,2,0\">Montage de meubles selon les instructions<\/p><\/li><li><p data-path-to-node=\"17,3,0\">Emballage soigneux des meubles finis pour l'exp\u00e9dition<\/p><\/li><\/ul><p data-path-to-node=\"18\"><b data-path-to-node=\"18\" data-index-in-node=\"0\">Ton profil<\/b><\/p><ul data-path-to-node=\"19\"><li><p data-path-to-node=\"19,0,0\">Tu aimes le travail manuel et tu aimes mettre la main \u00e0 la p\u00e2te.<\/p><\/li><li><p data-path-to-node=\"19,1,0\">Une premi\u00e8re exp\u00e9rience dans le maniement du bois ou dans le montage est super, mais <b data-path-to-node=\"19,1,0\" data-index-in-node=\"74\">pas obligatoire<\/b> - les personnes motiv\u00e9es qui changent d'orientation professionnelle (m\/f) sont \u00e9galement les bienvenues chez nous !<\/p><\/li><li><p data-path-to-node=\"19,2,0\">Tu travailles avec soin, de mani\u00e8re fiable et dans le respect de la qualit\u00e9.<\/p><\/li><li><p data-path-to-node=\"19,3,0\">Tu appr\u00e9cies un environnement de travail calme, concentr\u00e9 et coll\u00e9gial.<\/p><\/li><\/ul><p data-path-to-node=\"20\"><b data-path-to-node=\"20\" data-index-in-node=\"0\">Nous t'offrons<\/b><\/p><ul data-path-to-node=\"21\"><li><p data-path-to-node=\"21,0,0\"><b data-path-to-node=\"21,0,0\" data-index-in-node=\"0\">Salaire horaire \u00e9quitable :<\/b> 15 \u00e0 20 \u20ac par heure<\/p><\/li><li><p data-path-to-node=\"21,1,0\"><b data-path-to-node=\"21,1,0\" data-index-in-node=\"0\">Mod\u00e8le de mini-job :<\/b> Id\u00e9al comme revenu d'appoint.<\/p><\/li><li><p data-path-to-node=\"21,2,0\"><b data-path-to-node=\"21,2,0\" data-index-in-node=\"0\">la flexibilit\u00e9 :<\/b> Les horaires de travail peuvent \u00eatre am\u00e9nag\u00e9s de mani\u00e8re flexible, apr\u00e8s concertation, afin de s'adapter au mieux \u00e0 ton quotidien.<\/p><\/li><li><p data-path-to-node=\"21,3,0\"><b data-path-to-node=\"21,3,0\" data-index-in-node=\"0\">Environnement d\u00e9tendu :<\/b> Un travail sans pression constante, mais avec une \u00e9quipe formidable et du bon caf\u00e9.<\/p><\/li><\/ul><p data-path-to-node=\"22\"><b data-path-to-node=\"22\" data-index-in-node=\"0\">\u00c7a te semble bien ? Alors contacte-nous !<\/b> Nous n'avons pas besoin d'une lettre de motivation longue et compliqu\u00e9e. Contacte-nous simplement - <a href=\"mailto:info@vanfittery.de\">par e-mail<\/a>, <a href=\"tel:+4915124124296\">par t\u00e9l\u00e9phone<\/a> ou via notre <a href=\"https:\/\/vanfittery.de\/fr\/contact\/\" target=\"_blank\" rel=\"noopener\">Formulaire de contact<\/a>. Dis-nous en quelques phrases qui tu es et \u00e0 partir de quand tu pourrais commencer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8003d5e elementor-widget elementor-widget-html\" data-id=\"8003d5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\\\/\",\n    \"@type\": \"JobPosting\",\n    \"title\": \"Mitarbeiter in der Produktion \\\/ Holzverarbeitung (m\\\/w\\\/d) auf Minijob-Basis\",\n    \"description\": \"<p>Du hast Lust auf handwerkliche Arbeit in einer entspannten Umgebung? F\\u00fcr unsere Produktion in Postau suchen wir ab sofort tatkr\\u00e4ftige Unterst\\u00fctzung auf Minijob-Basis.<\\\/p><p><strong>Deine Aufgaben:<\\\/strong><\\\/p><ul><li>Handwerkliche T\\u00e4tigkeiten und allgemeine Unterst\\u00fctzung in der Produktion<\\\/li><li>Arbeiten mit verschiedenen Holzmaterialien<\\\/li><li>Montage von M\\u00f6belst\\u00fccken nach Vorgabe<\\\/li><li>Sorgf\\u00e4ltiges Verpacken der fertigen M\\u00f6bel f\\u00fcr den Versand<\\\/li><\\\/ul><p><strong>Dein Profil:<\\\/strong><\\\/p><ul><li>Du hast Freude an handwerklicher Arbeit und packst gerne mit an.<\\\/li><li>Erste Erfahrungen im Umgang mit Holz oder in der Montage sind super, aber kein Muss (Quereinsteiger willkommen).<\\\/li><li>Du arbeitest sorgf\\u00e4ltig, zuverl\\u00e4ssig und qualit\\u00e4tsbewusst.<\\\/li><\\\/ul><p><strong>Wir bieten dir:<\\\/strong><\\\/p><ul><li>Stundenlohn: 15 bis 20 \\u20ac pro Stunde.<\\\/li><li>Minijob-Modell f\\u00fcr maximale Flexibilit\\u00e4t.<\\\/li><li>Eine friedfertige Arbeit ohne st\\u00e4ndigen Druck in einem tollen Team.<\\\/li><\\\/ul>\",\n    \"identifier\": {\n        \"@type\": \"PropertyValue\",\n        \"name\": \"Vanfittery\",\n        \"value\": \"VF-PROD-2026-01\"\n    },\n    \"datePosted\": \"2026-03-17\",\n    \"validThrough\": \"2026-06-30T23:59\",\n    \"employmentType\": \"PART_TIME\",\n    \"hiringOrganization\": {\n        \"@type\": \"Organization\",\n        \"name\": \"Vanfittery\",\n        \"sameAs\": \"https:\\\/\\\/vanfittery.de\"\n    },\n    \"jobLocation\": {\n        \"@type\": \"Place\",\n        \"address\": {\n            \"@type\": \"PostalAddress\",\n            \"streetAddress\": \"Hauptstra\\u00dfe 40\",\n            \"addressLocality\": \"Postau\",\n            \"addressRegion\": \"Bayern\",\n            \"postalCode\": \"84103\",\n            \"addressCountry\": \"DE\"\n        }\n    },\n    \"baseSalary\": {\n        \"@type\": \"MonetaryAmount\",\n        \"currency\": \"EUR\",\n        \"value\": {\n            \"@type\": \"QuantitativeValue\",\n            \"minValue\": 15,\n            \"maxValue\": 20,\n            \"unitText\": \"HOUR\"\n        }\n    }\n}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e60ae90 gpt e-flex e-con-boxed e-con e-parent\" data-id=\"e60ae90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7c8c7e8 e-con-full sw e-flex e-con e-child\" data-id=\"7c8c7e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b90b658 elementor-widget elementor-widget-heading\" data-id=\"b90b658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Actuellement, nous recherchons :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f871cb6 sw smt elementor-widget elementor-widget-n-accordion\" data-id=\"f871cb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;max_items_expended&quot;:&quot;multiple&quot;,&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"L&#039;accord\u00e9on. Ouvre les liens avec Enter ou Space, ferme avec Escape, et navigue avec Arrow Keys.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2600\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2600\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Employ\u00e9(e) de production \/ transformation du bois (m\/f) sur la base d'un mini-job <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2600\" class=\"elementor-element elementor-element-4c6100a e-con-full e-flex e-con e-child\" data-id=\"4c6100a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc8a62 elementor-widget elementor-widget-text-editor\" data-id=\"5fc8a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"14\"><b data-path-to-node=\"14\" data-index-in-node=\"0\">Emplacement :<\/b> Postau | <b data-path-to-node=\"14\" data-index-in-node=\"19\">Art :<\/b> Minijob (jusqu'\u00e0 603 \u20ac) | <b data-path-to-node=\"14\" data-index-in-node=\"46\">Salaire :<\/b> 15 - 20 \u20ac \/ heure<\/p><p data-path-to-node=\"15\"><b data-path-to-node=\"15\" data-index-in-node=\"0\">A propos du travail :<\/b> Tu as envie d'un travail manuel dans un environnement d\u00e9tendu ? Pour notre production \u00e0 Postau, nous recherchons d\u00e8s maintenant un soutien actif sur la base d'un mini-job. Il r\u00e8gne chez nous une atmosph\u00e8re de travail paisible et concentr\u00e9e - id\u00e9ale pour tous ceux qui aiment travailler de leurs mains et veulent voir un r\u00e9sultat tangible \u00e0 la fin de la journ\u00e9e.<\/p><p data-path-to-node=\"16\"><b data-path-to-node=\"16\" data-index-in-node=\"0\">Tes t\u00e2ches :<\/b><\/p><ul data-path-to-node=\"17\"><li><p data-path-to-node=\"17,0,0\">Activit\u00e9s manuelles et soutien g\u00e9n\u00e9ral \u00e0 la production<\/p><\/li><li><p data-path-to-node=\"17,1,0\">Travailler avec diff\u00e9rents mat\u00e9riaux en bois<\/p><\/li><li><p data-path-to-node=\"17,2,0\">Montage de meubles selon les instructions<\/p><\/li><li><p data-path-to-node=\"17,3,0\">Emballage soigneux des meubles finis pour l'exp\u00e9dition<\/p><\/li><\/ul><p data-path-to-node=\"18\"><b data-path-to-node=\"18\" data-index-in-node=\"0\">Ton profil<\/b><\/p><ul data-path-to-node=\"19\"><li><p data-path-to-node=\"19,0,0\">Tu aimes le travail manuel et tu aimes mettre la main \u00e0 la p\u00e2te.<\/p><\/li><li><p data-path-to-node=\"19,1,0\">Une premi\u00e8re exp\u00e9rience dans le maniement du bois ou dans le montage est super, mais <b data-path-to-node=\"19,1,0\" data-index-in-node=\"74\">pas obligatoire<\/b> - les personnes motiv\u00e9es qui changent d'orientation professionnelle (m\/f) sont \u00e9galement les bienvenues chez nous !<\/p><\/li><li><p data-path-to-node=\"19,2,0\">Tu travailles avec soin, de mani\u00e8re fiable et dans le respect de la qualit\u00e9.<\/p><\/li><li><p data-path-to-node=\"19,3,0\">Tu appr\u00e9cies un environnement de travail calme, concentr\u00e9 et coll\u00e9gial.<\/p><\/li><\/ul><p data-path-to-node=\"20\"><b data-path-to-node=\"20\" data-index-in-node=\"0\">Nous t'offrons<\/b><\/p><ul data-path-to-node=\"21\"><li><p data-path-to-node=\"21,0,0\"><b data-path-to-node=\"21,0,0\" data-index-in-node=\"0\">Salaire horaire \u00e9quitable :<\/b> 15 \u00e0 20 \u20ac par heure<\/p><\/li><li><p data-path-to-node=\"21,1,0\"><b data-path-to-node=\"21,1,0\" data-index-in-node=\"0\">Mod\u00e8le de mini-job :<\/b> Id\u00e9al comme revenu d'appoint.<\/p><\/li><li><p data-path-to-node=\"21,2,0\"><b data-path-to-node=\"21,2,0\" data-index-in-node=\"0\">la flexibilit\u00e9 :<\/b> Les horaires de travail peuvent \u00eatre am\u00e9nag\u00e9s de mani\u00e8re flexible, apr\u00e8s concertation, afin de s'adapter au mieux \u00e0 ton quotidien.<\/p><\/li><li><p data-path-to-node=\"21,3,0\"><b data-path-to-node=\"21,3,0\" data-index-in-node=\"0\">Environnement d\u00e9tendu :<\/b> Un travail sans pression constante, mais avec une \u00e9quipe formidable et du bon caf\u00e9.<\/p><\/li><\/ul><p data-path-to-node=\"22\"><b data-path-to-node=\"22\" data-index-in-node=\"0\">\u00c7a te semble bien ? Alors contacte-nous !<\/b> Nous n'avons pas besoin d'une lettre de motivation longue et compliqu\u00e9e. Contacte-nous simplement - <a href=\"mailto:info@vanfittery.de\">par e-mail<\/a>, <a href=\"tel:+4915124124296\">par t\u00e9l\u00e9phone<\/a> ou via notre <a href=\"https:\/\/vanfittery.de\/fr\/contact\/\" target=\"_blank\" rel=\"noopener\">Formulaire de contact<\/a>. Dis-nous en quelques phrases qui tu es et \u00e0 partir de quand tu pourrais commencer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0857943 elementor-widget elementor-widget-html\" data-id=\"0857943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\\\/\",\n    \"@type\": \"JobPosting\",\n    \"title\": \"Mitarbeiter in der Produktion \\\/ Holzverarbeitung (m\\\/w\\\/d) auf Minijob-Basis\",\n    \"description\": \"<p>Du hast Lust auf handwerkliche Arbeit in einer entspannten Umgebung? F\\u00fcr unsere Produktion in Postau suchen wir ab sofort tatkr\\u00e4ftige Unterst\\u00fctzung auf Minijob-Basis.<\\\/p><p><strong>Deine Aufgaben:<\\\/strong><\\\/p><ul><li>Handwerkliche T\\u00e4tigkeiten und allgemeine Unterst\\u00fctzung in der Produktion<\\\/li><li>Arbeiten mit verschiedenen Holzmaterialien<\\\/li><li>Montage von M\\u00f6belst\\u00fccken nach Vorgabe<\\\/li><li>Sorgf\\u00e4ltiges Verpacken der fertigen M\\u00f6bel f\\u00fcr den Versand<\\\/li><\\\/ul><p><strong>Dein Profil:<\\\/strong><\\\/p><ul><li>Du hast Freude an handwerklicher Arbeit und packst gerne mit an.<\\\/li><li>Erste Erfahrungen im Umgang mit Holz oder in der Montage sind super, aber kein Muss (Quereinsteiger willkommen).<\\\/li><li>Du arbeitest sorgf\\u00e4ltig, zuverl\\u00e4ssig und qualit\\u00e4tsbewusst.<\\\/li><\\\/ul><p><strong>Wir bieten dir:<\\\/strong><\\\/p><ul><li>Stundenlohn: 15 bis 20 \\u20ac pro Stunde.<\\\/li><li>Minijob-Modell f\\u00fcr maximale Flexibilit\\u00e4t.<\\\/li><li>Eine friedfertige Arbeit ohne st\\u00e4ndigen Druck in einem tollen Team.<\\\/li><\\\/ul>\",\n    \"identifier\": {\n        \"@type\": \"PropertyValue\",\n        \"name\": \"Vanfittery\",\n        \"value\": \"VF-PROD-2026-01\"\n    },\n    \"datePosted\": \"2026-03-17\",\n    \"validThrough\": \"2026-06-30T23:59\",\n    \"employmentType\": \"PART_TIME\",\n    \"hiringOrganization\": {\n        \"@type\": \"Organization\",\n        \"name\": \"Vanfittery\",\n        \"sameAs\": \"https:\\\/\\\/vanfittery.de\"\n    },\n    \"jobLocation\": {\n        \"@type\": \"Place\",\n        \"address\": {\n            \"@type\": \"PostalAddress\",\n            \"streetAddress\": \"Hauptstra\\u00dfe 40\",\n            \"addressLocality\": \"Postau\",\n            \"addressRegion\": \"Bayern\",\n            \"postalCode\": \"84103\",\n            \"addressCountry\": \"DE\"\n        }\n    },\n    \"baseSalary\": {\n        \"@type\": \"MonetaryAmount\",\n        \"currency\": \"EUR\",\n        \"value\": {\n            \"@type\": \"QuantitativeValue\",\n            \"minValue\": 15,\n            \"maxValue\": 20,\n            \"unitText\": \"HOUR\"\n        }\n    }\n}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2601\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2601\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Couturier(\u00e8re) \/ Travailleur(se) textile (h\/f) sur la base d'un mini-job <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2601\" class=\"elementor-element elementor-element-e18fdbe e-con-full e-flex e-con e-child\" data-id=\"e18fdbe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e6213d elementor-widget elementor-widget-text-editor\" data-id=\"3e6213d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"14\"><b data-path-to-node=\"14\" data-index-in-node=\"0\">Emplacement :<\/b> Postau | <b data-path-to-node=\"14\" data-index-in-node=\"19\">Art :<\/b> Minijob (jusqu'\u00e0 603 \u20ac) | <b data-path-to-node=\"14\" data-index-in-node=\"46\">Salaire :<\/b> 15 - 20 \u20ac \/ heure<\/p><p data-path-to-node=\"15\"><b data-path-to-node=\"15\" data-index-in-node=\"0\">A propos du travail :<\/b> Tu as le sens du tissu et la machine \u00e0 coudre est ta meilleure amie ? Nous recherchons d\u00e8s maintenant de l'aide pour notre production \u00e0 Postau, sur la base d'un mini-job. Nous fabriquons des matelas pour campeurs et avons besoin de quelqu'un pour confectionner des housses parfaitement adapt\u00e9es \u00e0 partir de nos tissus d\u00e9coup\u00e9s. Il r\u00e8gne chez nous une atmosph\u00e8re de travail paisible et concentr\u00e9e - id\u00e9ale pour tous ceux qui aiment le travail pratique et veulent voir un r\u00e9sultat tangible \u00e0 la fin de la journ\u00e9e.<\/p><p data-path-to-node=\"16\"><b data-path-to-node=\"16\" data-index-in-node=\"0\">Tes t\u00e2ches :<\/b><\/p><ul data-path-to-node=\"17\"><li>\u00a0D\u00e9coupe de tissus ou de housses et de mousse de matelas.<\/li><li><p>Couture de housses de matelas et de coussins selon des gabarits pr\u00e9d\u00e9finis.<\/p><\/li><li><p>Contr\u00f4le de la qualit\u00e9 des housses finies (fermetures \u00e9clair, coutures).<\/p><\/li><li>Aide \u00e0 l'emballage et pr\u00e9paration \u00e0 l'exp\u00e9dition<\/li><\/ul><p data-path-to-node=\"18\"><b data-path-to-node=\"18\" data-index-in-node=\"0\">Ton profil<\/b><\/p><ul data-path-to-node=\"19\"><li><p data-path-to-node=\"19,0,0\">Tu as une solide exp\u00e9rience de la machine \u00e0 coudre (que ce soit par le biais d'une exp\u00e9rience professionnelle, en tant que couturier(\u00e8re), tapissier(\u00e8re) ou en tant que couturier(\u00e8re) amateur(e) tr\u00e8s passionn\u00e9(e)).<\/p><\/li><li><p data-path-to-node=\"19,2,0\">Tu travailles avec soin, tu es fiable et tu as le sens de la qualit\u00e9.<\/p><\/li><li><p data-path-to-node=\"19,3,0\">Tu appr\u00e9cies un environnement de travail calme, concentr\u00e9 et coll\u00e9gial.<\/p><\/li><\/ul><p data-path-to-node=\"20\"><b data-path-to-node=\"20\" data-index-in-node=\"0\">Nous t'offrons<\/b><\/p><ul data-path-to-node=\"21\"><li><p data-path-to-node=\"21,0,0\"><b data-path-to-node=\"21,0,0\" data-index-in-node=\"0\">Salaire horaire \u00e9quitable :<\/b> 15 \u00e0 20 \u20ac par heure<\/p><\/li><li><p data-path-to-node=\"21,1,0\"><b data-path-to-node=\"21,1,0\" data-index-in-node=\"0\">Mod\u00e8le de mini-job :<\/b> Id\u00e9al comme revenu d'appoint, \u00e9galement pour les retrait\u00e9(e)s.<\/p><\/li><li><p data-path-to-node=\"21,2,0\"><b data-path-to-node=\"21,2,0\" data-index-in-node=\"0\">la flexibilit\u00e9 :<\/b> Les horaires de travail peuvent \u00eatre am\u00e9nag\u00e9s de mani\u00e8re flexible, apr\u00e8s concertation, afin de s'adapter au mieux \u00e0 ton quotidien.<\/p><\/li><li><p data-path-to-node=\"21,3,0\"><b data-path-to-node=\"21,3,0\" data-index-in-node=\"0\">Environnement d\u00e9tendu :<\/b> Un travail sans pression constante, mais avec une \u00e9quipe formidable et du bon caf\u00e9.<\/p><\/li><\/ul><p data-path-to-node=\"22\"><b data-path-to-node=\"22\" data-index-in-node=\"0\">\u00c7a te semble bien ? Alors contacte-nous !<\/b> Nous n'avons pas besoin d'une lettre de motivation longue et compliqu\u00e9e. Contacte-nous simplement - <a href=\"mailto:info@vanfittery.de\">par e-mail<\/a>, <a href=\"tel:+4915124124296\">par t\u00e9l\u00e9phone<\/a> ou via notre <a href=\"https:\/\/vanfittery.de\/fr\/contact\/\" target=\"_blank\" rel=\"noopener\">Formulaire de contact<\/a>. Dis-nous en quelques phrases qui tu es, d'o\u00f9 vient ton exp\u00e9rience en mati\u00e8re de couture et \u00e0 partir de quand tu pourrais commencer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b68ba0 elementor-widget elementor-widget-html\" data-id=\"9b68ba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\\\/\",\n    \"@type\": \"JobPosting\",\n    \"title\": \"N\\u00e4her\\\/in \\\/ Textilverarbeiter\\\/in (m\\\/w\\\/d) auf Minijob-Basis\",\n    \"description\": \"<p>Du hast ein H\\u00e4ndchen f\\u00fcr Stoffe und die N\\u00e4hmaschine ist dein bester Freund? F\\u00fcr unsere Produktion in Postau suchen wir ab sofort Unterst\\u00fctzung auf Minijob-Basis. Wir stellen Camper-Matratzen her und brauchen jemanden, der aus unseren zugeschnittenen Stoffen passgenaue Bez\\u00fcge zaubert. Bei uns herrscht eine friedfertige und fokussierte Arbeitsatmosph\\u00e4re \\u2013 ideal f\\u00fcr alle, die gerne praktisch arbeiten und am Ende des Tages ein greifbares Ergebnis sehen wollen.<\\\/p><p><strong>Deine Aufgaben:<\\\/strong><\\\/p><ul><li>Zuschnitt von Stoffen bzw. Bez\\u00fcgen und Matratzen-Schaumstoff.<\\\/li><li>N\\u00e4hen von Matratzen- und Polsterbez\\u00fcgen nach vorgegebenen Schablonen.<\\\/li><li>Qualit\\u00e4tskontrolle der fertigen Bez\\u00fcge (Rei\\u00dfverschl\\u00fcsse, N\\u00e4hte).<\\\/li><li>Unterst\\u00fctzung beim Verpacken und Vorbereitung f\\u00fcr den Versand<\\\/li><\\\/ul><p><strong>Dein Profil:<\\\/strong><\\\/p><ul><li>Du hast solide Erfahrung an der N\\u00e4hmaschine (egal ob durch Berufserfahrung, als Schneider\\\/in, Polsterer\\\/in oder als sehr passionierte\\\/r Hobby-N\\u00e4her\\\/in).<\\\/li><li>Du arbeitest sorgf\\u00e4ltig, zuverl\\u00e4ssig und hast einen Blick f\\u00fcr Qualit\\u00e4t.<\\\/li><li>Du sch\\u00e4tzt ein ruhiges, konzentriertes und kollegiales Arbeitsumfeld.<\\\/li><\\\/ul><p><strong>Wir bieten dir:<\\\/strong><\\\/p><ul><li>Fairer Stundenlohn: 15 bis 20 \\u20ac pro Stunde<\\\/li><li>Minijob-Modell: Ideal als Nebenverdienst, auch f\\u00fcr Rentner\\\/innen.<\\\/li><li>Flexibilit\\u00e4t: Die Arbeitszeiten k\\u00f6nnen wir nach Absprache flexibel gestalten, sodass sie bestm\\u00f6glich in deinen Alltag passen.<\\\/li><li>Entspanntes Umfeld: Eine Arbeit ohne st\\u00e4ndigen Druck, daf\\u00fcr mit einem tollen Team und gutem Kaffee.<\\\/li><\\\/ul>\",\n    \"identifier\": {\n        \"@type\": \"PropertyValue\",\n        \"name\": \"Vanfittery\",\n        \"value\": \"VF-TEXTIL-2026-01\"\n    },\n    \"datePosted\": \"2026-03-31\",\n    \"validThrough\": \"2026-06-30T23:59\",\n    \"employmentType\": \"PART_TIME\",\n    \"hiringOrganization\": {\n        \"@type\": \"Organization\",\n        \"name\": \"Vanfittery\",\n        \"sameAs\": \"https:\\\/\\\/vanfittery.de\"\n    },\n    \"jobLocation\": {\n        \"@type\": \"Place\",\n        \"address\": {\n            \"@type\": \"PostalAddress\",\n            \"streetAddress\": \"Hauptstra\\u00dfe 40\",\n            \"addressLocality\": \"Postau\",\n            \"addressRegion\": \"Bayern\",\n            \"postalCode\": \"84103\",\n            \"addressCountry\": \"DE\"\n        }\n    },\n    \"baseSalary\": {\n        \"@type\": \"MonetaryAmount\",\n        \"currency\": \"EUR\",\n        \"value\": {\n            \"@type\": \"QuantitativeValue\",\n            \"minValue\": 15,\n            \"maxValue\": 20,\n            \"unitText\": \"HOUR\"\n        }\n    }\n}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-239d562 e-flex e-con-boxed e-con e-parent\" data-id=\"239d562\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a248ffd gp  e-con-full e-flex e-con e-child\" data-id=\"a248ffd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5b53f16 e-con-full sw e-flex e-con e-child\" data-id=\"5b53f16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-281d3d1 elementor-widget elementor-widget-heading\" data-id=\"281d3d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rejoins la famille Vanfittery !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b85579 elementor-widget elementor-widget-text-editor\" data-id=\"9b85579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bienvenue chez Vanfittery ! Nous aimons ce que nous faisons : Travailler avec le bois, cr\u00e9er des meubles de qualit\u00e9 et construire des choses de nos propres mains. Nous croyons que le bon travail se fait dans un environnement paisible et sans stress. C'est pourquoi nous misons sur une collaboration d'\u00e9gal \u00e0 \u00e9gal, des horaires de travail flexibles qui s'adaptent \u00e0 ta vie et une r\u00e9mun\u00e9ration \u00e9quitable.<\/p><p>Que tu sois un artisan exp\u00e9riment\u00e9 ou que tu aies simplement envie de mettre la main \u00e0 la p\u00e2te - si tu aimes l'odeur du bois et que tu veux voir \u00e0 la fin de la journ\u00e9e ce que tu as fait, tu es \u00e0 la bonne adresse chez nous.<\/p><p><strong>Pourquoi travailler chez nous ?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-934dc54 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"934dc54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>R\u00e9mun\u00e9ration \u00e9quitable :<\/b> Nous appr\u00e9cions ton travail - et cela se voit aussi sur le compte.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b> Flexibilit\u00e9 totale :<\/b>  Nous adaptons tes horaires de travail \u00e0 ta vie, et non l'inverse.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Climat de travail pacifique :<\/b>  Pas de stress inutile, mais une collaboration calme, concentr\u00e9e et coll\u00e9giale au sein de la production.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Place aux personnes qui changent d'orientation :<\/b>  Tu n'as pas besoin d'un brevet de ma\u00eetrise pour d\u00e9buter chez nous. Nous nous ferons un plaisir de te former !<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca1bf2e smt elementor-widget elementor-widget-testimonial\" data-id=\"ca1bf2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\u201eUn camping-car ne devient un chez-soi qu'avec les bons meubles. Et chez nous, ces meubles ne sont pas cr\u00e9\u00e9s sous pression \u00e0 la cha\u00eene, mais avec calme, fiert\u00e9 artisanale et une \u00e9quipe dans laquelle une collaboration d\u00e9tendue compte\u201c.\u201c<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/vanfittery.de\/wp-content\/uploads\/2024\/12\/tobias-czoppik-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1232\" alt=\"Tobias, fondateur de Vanfittery\" srcset=\"https:\/\/vanfittery.de\/wp-content\/uploads\/2024\/12\/tobias-czoppik-768x768.jpg 768w, https:\/\/vanfittery.de\/wp-content\/uploads\/2024\/12\/tobias-czoppik-100x100.jpg 100w, https:\/\/vanfittery.de\/wp-content\/uploads\/2024\/12\/tobias-czoppik-800x800.jpg 800w, https:\/\/vanfittery.de\/wp-content\/uploads\/2024\/12\/tobias-czoppik-300x300.jpg 300w, https:\/\/vanfittery.de\/wp-content\/uploads\/2024\/12\/tobias-czoppik-150x150.jpg 150w, https:\/\/vanfittery.de\/wp-content\/uploads\/2024\/12\/tobias-czoppik.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Tobi<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Fondateur de VANFITTERY<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Jobs &#8211; Werde Teil des Teams! Mitarbeiter in der Produktion \/ Holzverarbeitung (m\/w\/d) auf Minijob-Basis Standort: Postau | Art: Minijob (bis 603 \u20ac) | Gehalt: 15 \u2013 20 \u20ac \/ Stunde \u00dcber den Job: Du hast Lust auf handwerkliche Arbeit in einer entspannten Umgebung? F\u00fcr unsere Produktion in Postau suchen wir ab sofort tatkr\u00e4ftige Unterst\u00fctzung [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":85,"footnotes":""},"class_list":["post-13709","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/pages\/13709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/comments?post=13709"}],"version-history":[{"count":10,"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/pages\/13709\/revisions"}],"predecessor-version":[{"id":14342,"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/pages\/13709\/revisions\/14342"}],"wp:attachment":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/media?parent=13709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}