{"id":1527,"date":"2025-01-06T15:39:07","date_gmt":"2025-01-06T14:39:07","guid":{"rendered":"https:\/\/vanfittery.de\/datenschutz\/"},"modified":"2026-02-16T11:30:13","modified_gmt":"2026-02-16T10:30:13","slug":"protection-des-donnees","status":"publish","type":"page","link":"https:\/\/vanfittery.de\/fr\/datenschutz\/","title":{"rendered":"Protection des donn\u00e9es"},"content":{"rendered":"<h1 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Introduction<\/h2>\n\n\n\n<p>Par la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es, nous souhaitons vous expliquer quels types de donn\u00e9es \u00e0 caract\u00e8re personnel (ci-apr\u00e8s \u00e9galement d\u00e9sign\u00e9es par le terme \u201edonn\u00e9es\u201c) nous traitons, \u00e0 quelles fins et dans quelle mesure. La d\u00e9claration de protection des donn\u00e9es s'applique \u00e0 tous les traitements de donn\u00e9es \u00e0 caract\u00e8re personnel que nous effectuons, aussi bien dans le cadre de la fourniture de nos prestations que, en particulier, sur nos sites web, mobiles, ainsi qu'au sein de nos pr\u00e9sences en ligne externes, comme par exemple nos profils de m\u00e9dias sociaux (ci-apr\u00e8s d\u00e9nomm\u00e9s collectivement \u201eoffre en ligne\u201c).<\/p>\n\n\n\n<p>Les termes utilis\u00e9s ne sont pas sexu\u00e9s.<\/p>\n\n\n\n<p>Version : 16.02.2026<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aper\u00e7u du contenu<\/h2>\n\n\n\n<ul class=\"wp-block-list index\">\n<li><a class=\"index-link\" href=\"#m14\">Introduction<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m3\">Responsable<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#mOverview\">Aper\u00e7u des traitements<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m11\">Contact d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m13\">Bases juridiques pertinentes<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m27\">Mesures de s\u00e9curit\u00e9<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m25\">Transfert et divulgation de donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m24\">Traitement des donn\u00e9es dans les pays tiers<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m134\">Utilisation de cookies<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m317\">Services commerciaux et professionnels<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m326\">Prestataire de services de paiement<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m325\">Contr\u00f4le de solvabilit\u00e9<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m225\">Mise \u00e0 disposition de l'offre en ligne et h\u00e9bergement web<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m182\">Prise de contact<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m17\">Bulletins d'information et notifications \u00e9lectroniques<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m263\">Analyse web, suivi et optimisation<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m264\">Marketing en ligne<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m136\">Pr\u00e9sences dans les r\u00e9seaux sociaux (Social Media)<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m328\">Plugins et fonctions int\u00e9gr\u00e9es et contenus<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m12\">Suppression des donn\u00e9es<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m15\">Modification et mise \u00e0 jour de la d\u00e9claration de confidentialit\u00e9<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m10\">Droits des personnes concern\u00e9es<\/a><\/li>\n\n\n\n<li><a class=\"index-link\" href=\"#m42\">D\u00e9finitions des termes<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m3\">Responsable<\/h2>\n\n\n\n<p>VANFITTERY - CzoppikEngineering GmbH<br>Tobias Czoppik<br>Rue principale 40<br>84103 Postau<br>Allemagne<\/p>\n\n\n\n<p><strong>Adresse \u00e9lectronique :<\/strong> info@vanfittery.de<\/p>\n\n\n\n<p><strong>T\u00e9l\u00e9phone :<\/strong> +49 (0) 1512 \/ 412 42 96<\/p>\n\n\n\n<p><strong>Mentions l\u00e9gales :<\/strong> <a href=\"https:\/\/vanfittery.de\/fr\/mentions-legales\/\">https:\/\/vanfittery.de\/impressum<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mOverview\">Aper\u00e7u des traitements<\/h2>\n\n\n\n<p>L'aper\u00e7u ci-dessous r\u00e9sume les types de donn\u00e9es trait\u00e9es et les finalit\u00e9s de leur traitement et renvoie aux personnes concern\u00e9es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Types de donn\u00e9es trait\u00e9es<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>donn\u00e9es d'inventaire (par ex. noms, adresses).<\/li>\n\n\n\n<li>donn\u00e9es de contenu (par exemple, les entr\u00e9es dans les formulaires en ligne).<\/li>\n\n\n\n<li>les coordonn\u00e9es (par ex. e-mail, num\u00e9ros de t\u00e9l\u00e9phone).<\/li>\n\n\n\n<li>M\u00e9tadonn\u00e9es\/donn\u00e9es de communication (par ex. informations sur les appareils, adresses IP).<\/li>\n\n\n\n<li>donn\u00e9es d'utilisation (par ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s).<\/li>\n\n\n\n<li>donn\u00e9es de localisation (informations sur la position g\u00e9ographique d'un appareil ou d'une personne).<\/li>\n\n\n\n<li>donn\u00e9es contractuelles (par ex. objet du contrat, dur\u00e9e, cat\u00e9gorie de clients).<\/li>\n\n\n\n<li>donn\u00e9es de paiement (par ex. coordonn\u00e9es bancaires, factures, historique des paiements).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Cat\u00e9gories de personnes concern\u00e9es<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>partenaires commerciaux et contractuels.<\/li>\n\n\n\n<li>Les personnes int\u00e9ress\u00e9es.<\/li>\n\n\n\n<li>Partenaires de communication.<\/li>\n\n\n\n<li>des clients.<\/li>\n\n\n\n<li>Utilisateurs (par exemple, visiteurs de sites web, utilisateurs de services en ligne).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Finalit\u00e9s du traitement<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c9valuation de la solvabilit\u00e9 et du cr\u00e9dit.<\/li>\n\n\n\n<li>Mise \u00e0 disposition de notre offre en ligne et convivialit\u00e9.<\/li>\n\n\n\n<li>\u00c9valuation de l'action de visite.<\/li>\n\n\n\n<li>Proc\u00e9dures de bureau et d'organisation.<\/li>\n\n\n\n<li>le cross-device tracking (traitement des donn\u00e9es des utilisateurs sur plusieurs appareils \u00e0 des fins de marketing).<\/li>\n\n\n\n<li>le marketing direct (par exemple, par courrier \u00e9lectronique ou postal).<\/li>\n\n\n\n<li>Marketing bas\u00e9 sur les int\u00e9r\u00eats et le comportement.<\/li>\n\n\n\n<li>Demandes de contact et communication.<\/li>\n\n\n\n<li>mesure de la conversion (mesure de l'efficacit\u00e9 des mesures de marketing).<\/li>\n\n\n\n<li>le profilage (cr\u00e9ation de profils d'utilisateurs).<\/li>\n\n\n\n<li>Le remarketing.<\/li>\n\n\n\n<li>Mesure de la port\u00e9e (par ex. statistiques d'acc\u00e8s, reconnaissance des visiteurs r\u00e9currents).<\/li>\n\n\n\n<li>Mesures de s\u00e9curit\u00e9.<\/li>\n\n\n\n<li>le suivi (par ex. profilage bas\u00e9 sur les int\u00e9r\u00eats\/le comportement, utilisation de cookies).<\/li>\n\n\n\n<li>Fourniture de prestations contractuelles et service \u00e0 la client\u00e8le.<\/li>\n\n\n\n<li>Gestion et r\u00e9ponse aux demandes.<\/li>\n\n\n\n<li>Ciblage (d\u00e9termination de groupes cibles pertinents \u00e0 des fins de marketing ou autre \u00e9dition de contenu).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">D\u00e9cisions automatis\u00e9es dans des cas individuels<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Renseignements sur la solvabilit\u00e9 (d\u00e9cision bas\u00e9e sur une v\u00e9rification de la solvabilit\u00e9).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"m13\">Bases juridiques pertinentes<\/h3>\n\n\n\n<p>Nous vous communiquons ci-apr\u00e8s les bases juridiques du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) sur lesquelles nous nous basons pour traiter les donn\u00e9es personnelles. Veuillez noter qu'en plus des dispositions du RGPD, les directives nationales en mati\u00e8re de protection des donn\u00e9es peuvent s'appliquer dans votre pays ou dans notre pays de r\u00e9sidence et de domicile. Si, dans un cas particulier, des bases juridiques plus sp\u00e9cifiques devaient \u00eatre d\u00e9terminantes, nous vous les communiquerions dans la d\u00e9claration de protection des donn\u00e9es.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Consentement (art. 6, al. 1, p. 1, let. a. RGPD)<\/strong> - La personne concern\u00e9e a donn\u00e9 son consentement au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel la concernant pour une ou plusieurs finalit\u00e9s d\u00e9termin\u00e9es.<\/li>\n\n\n\n<li><strong>Ex\u00e9cution d'un contrat et demandes pr\u00e9contractuelles (art. 6, par. 1, p. 1, let. b. RGPD)<\/strong> - Le traitement est n\u00e9cessaire \u00e0 l'ex\u00e9cution d'un contrat auquel la personne concern\u00e9e est partie ou \u00e0 l'ex\u00e9cution de mesures pr\u00e9contractuelles prises \u00e0 la demande de la personne concern\u00e9e.<\/li>\n\n\n\n<li><strong>Obligation l\u00e9gale (art. 6, par. 1, p. 1, let. c. RGPD)<\/strong> - le traitement est n\u00e9cessaire au respect d'une obligation l\u00e9gale \u00e0 laquelle le responsable est soumis.<\/li>\n\n\n\n<li><strong>Int\u00e9r\u00eats l\u00e9gitimes (art. 6, al. 1, p. 1, let. f. RGPD)<\/strong> - le traitement est n\u00e9cessaire aux fins des int\u00e9r\u00eats l\u00e9gitimes poursuivis par le responsable du traitement ou par un tiers, \u00e0 moins que ne pr\u00e9valent les int\u00e9r\u00eats ou les libert\u00e9s et droits fondamentaux de la personne concern\u00e9e, qui exigent une protection des donn\u00e9es \u00e0 caract\u00e8re personnel.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m27\">Mesures de s\u00e9curit\u00e9<\/h2>\n\n\n\n<p>Nous prenons les mesures techniques et organisationnelles appropri\u00e9es, conform\u00e9ment aux exigences l\u00e9gales, en tenant compte de l'\u00e9tat de la technique, des co\u00fbts de mise en \u0153uvre et de la nature, de la port\u00e9e, des circonstances et des finalit\u00e9s du traitement, ainsi que des diff\u00e9rentes probabilit\u00e9s d'occurrence et du niveau de menace pour les droits et libert\u00e9s des personnes physiques, afin de garantir un niveau de protection adapt\u00e9 au risque.<\/p>\n\n\n\n<p>Ces mesures consistent notamment \u00e0 assurer la confidentialit\u00e9, l'int\u00e9grit\u00e9 et la disponibilit\u00e9 des donn\u00e9es en contr\u00f4lant l'acc\u00e8s physique et \u00e9lectronique aux donn\u00e9es, ainsi que l'acc\u00e8s, la saisie, la divulgation, la disponibilit\u00e9 et la s\u00e9paration des donn\u00e9es. Nous avons \u00e9galement mis en place des proc\u00e9dures pour garantir l'exercice des droits des personnes concern\u00e9es, l'effacement des donn\u00e9es et la r\u00e9ponse aux menaces pesant sur les donn\u00e9es. En outre, nous tenons compte de la protection des donn\u00e9es personnelles d\u00e8s le d\u00e9veloppement ou le choix du mat\u00e9riel, des logiciels et des proc\u00e9dures conform\u00e9ment au principe de la protection des donn\u00e9es, par la conception technique et par des param\u00e8tres par d\u00e9faut favorables \u00e0 la protection des donn\u00e9es.<\/p>\n\n\n\n<p><strong>Cryptage SSL (https)<\/strong>Pour prot\u00e9ger les donn\u00e9es que vous nous transmettez via notre offre en ligne, nous utilisons un cryptage SSL. Vous reconnaissez les connexions crypt\u00e9es par le pr\u00e9fixe https:\/\/ dans la ligne d'adresse de votre navigateur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m25\">Transfert et divulgation de donn\u00e9es \u00e0 caract\u00e8re personnel<\/h2>\n\n\n\n<p>Dans le cadre de notre traitement des donn\u00e9es \u00e0 caract\u00e8re personnel, il peut arriver que les donn\u00e9es soient transmises \u00e0 d'autres services, entreprises, unit\u00e9s organisationnelles juridiquement ind\u00e9pendantes ou personnes, ou qu'elles leur soient divulgu\u00e9es. Les destinataires de ces donn\u00e9es peuvent \u00eatre, par exemple, des \u00e9tablissements de paiement dans le cadre d'op\u00e9rations de paiement, des prestataires de services charg\u00e9s de t\u00e2ches informatiques ou des fournisseurs de services et de contenus int\u00e9gr\u00e9s \u00e0 un site web. Dans ce cas, nous respectons les dispositions l\u00e9gales et concluons en particulier les contrats ou accords correspondants avec les destinataires de vos donn\u00e9es, qui servent \u00e0 la protection de ces derni\u00e8res.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m24\">Traitement des donn\u00e9es dans les pays tiers<\/h2>\n\n\n\n<p>Si nous traitons des donn\u00e9es dans un pays tiers (c'est-\u00e0-dire en dehors de l'Union europ\u00e9enne (UE), de l'Espace \u00e9conomique europ\u00e9en (EEE)) ou si le traitement a lieu dans le cadre de l'utilisation de services de tiers ou de la divulgation ou du transfert de donn\u00e9es \u00e0 d'autres personnes, services ou entreprises, cela ne se fait que conform\u00e9ment aux dispositions l\u00e9gales.<\/p>\n\n\n\n<p>Sous r\u00e9serve d'un consentement explicite ou d'un transfert requis par contrat ou par la loi, nous ne traitons ou ne faisons traiter les donn\u00e9es que dans des pays tiers disposant d'un niveau de protection des donn\u00e9es reconnu, d'un engagement contractuel par le biais de clauses de protection standard de la Commission europ\u00e9enne, de l'existence de certifications ou de dispositions internes contraignantes en mati\u00e8re de protection des donn\u00e9es (art. 44 \u00e0 49 RGPD, page d'information de la Commission europ\u00e9enne : <a href=\"https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/international-dimension-data-protection_de\" target=\"_blank\" rel=\"noopener\">https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/international-dimension-data-protection_de<\/a> ).<\/p>\n\n\n\n<p>Dans le cadre du \u201eData Privacy Framework\u201d (DPF), la Commission europ\u00e9enne a \u00e9galement reconnu le niveau de protection des donn\u00e9es pour certaines entreprises am\u00e9ricaines dans le cadre de la d\u00e9cision d'ad\u00e9quation du 10 juillet 2023. La liste des entreprises certifi\u00e9es ainsi que d'autres informations sur le DPF peuvent \u00eatre consult\u00e9es sur le site Internet du minist\u00e8re am\u00e9ricain du commerce \u00e0 l'adresse suivante <a href=\"https:\/\/www.dataprivacyframework.gov\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.dataprivacyframework.gov\/<\/a> (en anglais) pour plus d'informations. Nous vous informons dans le cadre des informations sur la protection des donn\u00e9es quels sont les prestataires de services que nous utilisons et qui sont certifi\u00e9s selon le Data Privacy Framework.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m134\">Utilisation de cookies<\/h2>\n\n\n\n<p>Les cookies sont de petits fichiers texte, ou d'autres marques de m\u00e9moire, qui enregistrent des informations sur les terminaux et lisent des informations \u00e0 partir des terminaux. Par exemple, pour enregistrer le statut de connexion d'un compte utilisateur, le contenu d'un panier d'achat dans une boutique en ligne, les contenus consult\u00e9s ou les fonctions utilis\u00e9es d'une offre en ligne. Les cookies peuvent en outre \u00eatre utilis\u00e9s \u00e0 diff\u00e9rentes fins, par exemple \u00e0 des fins de fonctionnement, de s\u00e9curit\u00e9 et de confort des offres en ligne ainsi que pour l'\u00e9tablissement d'analyses des flux de visiteurs.<\/p>\n\n\n\n<p><strong>Remarques sur le consentement : <\/strong>Nous utilisons les cookies conform\u00e9ment aux dispositions l\u00e9gales. Par cons\u00e9quent, nous demandons le consentement pr\u00e9alable des utilisateurs, sauf si la loi ne l'exige pas. Le consentement n'est notamment pas n\u00e9cessaire si l'enregistrement et la lecture des informations, donc \u00e9galement des cookies, sont absolument indispensables pour fournir aux utilisateurs un t\u00e9l\u00e9service qu'ils ont express\u00e9ment demand\u00e9 (donc notre offre en ligne). Le consentement r\u00e9vocable est clairement communiqu\u00e9 aux utilisateurs et contient les informations relatives \u00e0 l'utilisation respective des cookies.<\/p>\n\n\n\n<p><strong>Remarques sur les bases juridiques relatives \u00e0 la protection des donn\u00e9es : <\/strong>La base juridique de la protection des donn\u00e9es sur laquelle nous traitons les donn\u00e9es personnelles des utilisateurs \u00e0 l'aide de cookies d\u00e9pend de la question de savoir si nous demandons le consentement des utilisateurs. Si les utilisateurs donnent leur consentement, la base juridique du traitement de leurs donn\u00e9es est le consentement d\u00e9clar\u00e9. Dans le cas contraire, les donn\u00e9es trait\u00e9es \u00e0 l'aide de cookies sont trait\u00e9es sur la base de nos int\u00e9r\u00eats l\u00e9gitimes (par exemple, l'exploitation commerciale de notre offre en ligne et l'am\u00e9lioration de son utilisabilit\u00e9) ou, si cela a lieu dans le cadre de l'ex\u00e9cution de nos obligations contractuelles, si l'utilisation de cookies est n\u00e9cessaire pour remplir nos obligations contractuelles. Les finalit\u00e9s pour lesquelles nous traitons les cookies sont expliqu\u00e9es dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es ou dans le cadre de nos processus de consentement et de traitement.<\/p>\n\n\n\n<p><strong>Dur\u00e9e de conservation : <\/strong>En ce qui concerne la dur\u00e9e de conservation, on distingue les types de cookies suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>les cookies temporaires (\u00e9galement appel\u00e9s cookies de session ou de s\u00e9ance) :<\/strong> Les cookies temporaires sont supprim\u00e9s au plus tard apr\u00e8s qu'un utilisateur a quitt\u00e9 une offre en ligne et ferm\u00e9 son terminal (par ex. navigateur ou application mobile).<\/li>\n\n\n\n<li><strong>Cookies permanents :<\/strong> Les cookies permanents restent enregistr\u00e9s m\u00eame apr\u00e8s la fermeture du terminal. Ils permettent par exemple d'enregistrer le statut de connexion ou d'afficher directement les contenus pr\u00e9f\u00e9r\u00e9s lorsque l'utilisateur consulte \u00e0 nouveau un site web. De m\u00eame, les donn\u00e9es des utilisateurs collect\u00e9es \u00e0 l'aide de cookies peuvent \u00eatre utilis\u00e9es pour mesurer la port\u00e9e. Dans la mesure o\u00f9 nous ne communiquons pas aux utilisateurs d'informations explicites sur la nature et la dur\u00e9e de stockage des cookies (par exemple dans le cadre de la demande de consentement), les utilisateurs doivent partir du principe que les cookies sont permanents et que leur dur\u00e9e de stockage peut aller jusqu'\u00e0 deux ans.<\/li>\n<\/ul>\n\n\n\n<p><strong>Informations g\u00e9n\u00e9rales sur la r\u00e9vocation et l'opposition (opt-out) : <\/strong> Selon que le traitement est effectu\u00e9 sur la base d'un consentement ou d'une autorisation l\u00e9gale, vous avez \u00e0 tout moment la possibilit\u00e9 de r\u00e9voquer un consentement donn\u00e9 ou de vous opposer au traitement de vos donn\u00e9es par les technologies de cookies (d\u00e9sign\u00e9 collectivement par le terme \u201eopt-out\u201c). Vous pouvez tout d'abord d\u00e9clarer votre opposition au moyen des param\u00e8tres de votre navigateur, par exemple en d\u00e9sactivant l'utilisation de cookies (ce qui peut \u00e9galement limiter le fonctionnement de notre offre en ligne). Une opposition \u00e0 l'utilisation de cookies \u00e0 des fins de marketing en ligne peut \u00e9galement \u00eatre formul\u00e9e au moyen d'un grand nombre de services, en particulier dans le cas du tracking, via les pages web <a href=\"https:\/\/optout.aboutads.info\" target=\"_blank\" rel=\"noopener\">https:\/\/optout.aboutads.info<\/a> et <a href=\"https:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youronlinechoices.com\/<\/a> de l'utilisateur. En outre, vous pouvez obtenir d'autres indications d'opposition dans le cadre des indications relatives aux prestataires de services et aux cookies utilis\u00e9s.<\/p>\n\n\n\n<p><strong>Traitement des donn\u00e9es des cookies sur la base d'un consentement :<\/strong> Nous utilisons une proc\u00e9dure de gestion du consentement aux cookies dans le cadre de laquelle les consentements des utilisateurs \u00e0 l'utilisation de cookies, ou aux traitements et fournisseurs mentionn\u00e9s dans le cadre de la proc\u00e9dure de gestion du consentement aux cookies, peuvent \u00eatre recueillis, g\u00e9r\u00e9s et r\u00e9voqu\u00e9s par les utilisateurs. Dans ce cas, la d\u00e9claration de consentement est enregistr\u00e9e afin de ne pas devoir r\u00e9p\u00e9ter sa demande et de pouvoir prouver le consentement conform\u00e9ment \u00e0 l'obligation l\u00e9gale. L'enregistrement peut avoir lieu c\u00f4t\u00e9 serveur et\/ou dans un cookie (cookie opt-in ou \u00e0 l'aide de technologies comparables) afin de pouvoir attribuer le consentement \u00e0 un utilisateur ou \u00e0 son appareil. Sous r\u00e9serve d'indications individuelles concernant les fournisseurs de services de gestion des cookies, les indications suivantes s'appliquent : La dur\u00e9e de conservation du consentement peut aller jusqu'\u00e0 deux ans. Dans ce cas, un identifiant pseudonyme de l'utilisateur est cr\u00e9\u00e9 et enregistr\u00e9 avec la date du consentement, des informations sur la port\u00e9e du consentement (par exemple, quelles cat\u00e9gories de cookies et\/ou quels fournisseurs de services) ainsi que le navigateur, le syst\u00e8me et le terminal utilis\u00e9.<\/p>\n\n\n\n<p><strong>Outil de consentement des cookies :<\/strong><\/p>\n\n\n\n<p>Nous utilisons l'outil de consentement \u201eReal Cookie Banner\u201c pour g\u00e9rer les cookies et les technologies similaires (pixels de suivi, balises web, etc.) et les consentements y aff\u00e9rents. Tu trouveras des d\u00e9tails sur le fonctionnement de \u201eReal Cookie Banner\u201c sous <a href=\"https:\/\/devowl.io\/de\/rcb\/datenverarbeitung\/\" rel=\"noreferrer noopener\" target=\"_blank\">https:\/\/devowl.io\/de\/rcb\/datenverarbeitung\/<\/a>.<\/p>\n\n\n\n<p>Les bases juridiques pour le traitement des donn\u00e9es personnelles dans ce contexte sont l'article 6, paragraphe 1, point c) du RGPD et l'article 6, paragraphe 1, point f) du RGPD. Notre int\u00e9r\u00eat l\u00e9gitime est la gestion des cookies et des technologies similaires utilis\u00e9s et des consentements y aff\u00e9rents.<\/p>\n\n\n\n<p>La mise \u00e0 disposition des donn\u00e9es personnelles n'est ni prescrite contractuellement ni n\u00e9cessaire \u00e0 la conclusion d'un contrat. Tu n'es pas oblig\u00e9 de fournir les donn\u00e9es personnelles. Si tu ne fournis pas les donn\u00e9es personnelles, nous ne pourrons pas g\u00e9rer tes consentements.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m317\">Services commerciaux et professionnels<\/h2>\n\n\n\n<p>Nous traitons les donn\u00e9es de nos partenaires contractuels et commerciaux, par exemple les clients et les personnes int\u00e9ress\u00e9es (d\u00e9sign\u00e9s collectivement comme \u201epartenaires contractuels\u201c) dans le cadre de relations juridiques contractuelles et comparables ainsi que de mesures connexes et dans le cadre de la communication avec les partenaires contractuels (ou pr\u00e9contractuelle), par exemple pour r\u00e9pondre \u00e0 des demandes.<\/p>\n\n\n\n<p>Nous traitons ces donn\u00e9es pour remplir nos obligations contractuelles, pour garantir nos droits et \u00e0 des fins de t\u00e2ches administratives li\u00e9es \u00e0 ces donn\u00e9es ainsi que pour l'organisation de l'entreprise. Dans le cadre du droit en vigueur, nous ne transmettons les donn\u00e9es des partenaires contractuels \u00e0 des tiers que dans la mesure o\u00f9 cela est n\u00e9cessaire aux fins susmentionn\u00e9es ou pour remplir des obligations l\u00e9gales, ou encore avec le consentement des personnes concern\u00e9es (par ex. aux services de t\u00e9l\u00e9communication, de transport et autres services auxiliaires impliqu\u00e9s ainsi qu'aux sous-traitants, aux banques, aux conseillers fiscaux et juridiques, aux prestataires de services de paiement ou aux autorit\u00e9s fiscales). Les partenaires contractuels sont inform\u00e9s des autres formes de traitement, par exemple \u00e0 des fins de marketing, dans le cadre de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n\n\n\n<p>Nous communiquons aux partenaires contractuels les donn\u00e9es n\u00e9cessaires aux fins susmentionn\u00e9es avant ou dans le cadre de la collecte des donn\u00e9es, par exemple dans les formulaires en ligne, par un marquage particulier (par ex. couleurs) ou des symboles (par ex. ast\u00e9risques ou autres), ou personnellement.<\/p>\n\n\n\n<p>Nous supprimons les donn\u00e9es \u00e0 l'expiration des obligations l\u00e9gales de garantie et des obligations comparables, c'est-\u00e0-dire, en principe, \u00e0 l'expiration d'un d\u00e9lai de 4 ans, sauf si les donn\u00e9es sont enregistr\u00e9es dans un compte client, par exemple, tant qu'elles doivent \u00eatre conserv\u00e9es pour des raisons l\u00e9gales d'archivage (par exemple, \u00e0 des fins fiscales, en r\u00e8gle g\u00e9n\u00e9rale, 10 ans). Si un d\u00e9lai ne commence pas express\u00e9ment \u00e0 une date pr\u00e9cise et qu'il est d'au moins un an, il commence automatiquement \u00e0 la fin de l'ann\u00e9e civile au cours de laquelle l'\u00e9v\u00e9nement d\u00e9clencheur du d\u00e9lai s'est produit. Dans le cas de relations contractuelles en cours dans le cadre desquelles des donn\u00e9es sont enregistr\u00e9es, l'\u00e9v\u00e9nement d\u00e9clencheur du d\u00e9lai est la date d'entr\u00e9e en vigueur de la r\u00e9siliation ou de toute autre cessation de la relation juridique. Les donn\u00e9es qui nous ont \u00e9t\u00e9 communiqu\u00e9es par le partenaire contractuel dans le cadre d'une commande sont effac\u00e9es conform\u00e9ment aux exigences de la commande, en principe apr\u00e8s la fin de la commande.<\/p>\n\n\n\n<p>Dans la mesure o\u00f9 nous faisons appel \u00e0 des fournisseurs tiers ou \u00e0 des plateformes pour fournir nos prestations, les conditions g\u00e9n\u00e9rales et les informations relatives \u00e0 la protection des donn\u00e9es des fournisseurs tiers ou des plateformes concern\u00e9s s'appliquent dans les relations entre les utilisateurs et les fournisseurs.<\/p>\n\n\n\n<p><strong>Compte client<\/strong>Les partenaires contractuels peuvent cr\u00e9er un compte au sein de notre offre en ligne (par ex. compte client ou compte utilisateur, en abr\u00e9g\u00e9 \u201ecompte client\u201c). Si l'enregistrement d'un compte client est n\u00e9cessaire, les partenaires contractuels en sont inform\u00e9s, de m\u00eame que des donn\u00e9es requises pour l'enregistrement. Les comptes clients ne sont pas publics et ne peuvent pas \u00eatre index\u00e9s par les moteurs de recherche. Dans le cadre de l'enregistrement ainsi que des inscriptions et utilisations ult\u00e9rieures du compte client, nous enregistrons les adresses IP des clients ainsi que les heures d'acc\u00e8s afin de pouvoir prouver l'enregistrement et pr\u00e9venir d'\u00e9ventuels abus du compte client.<\/p>\n\n\n\n<p>Lorsque les clients r\u00e9silient leur compte, les donn\u00e9es relatives \u00e0 ce compte sont supprim\u00e9es, sauf si leur conservation est n\u00e9cessaire pour des raisons l\u00e9gales. Il appartient aux clients de sauvegarder leurs donn\u00e9es lors de la r\u00e9siliation de leur compte client.<\/p>\n\n\n\n<p><strong>Analyses \u00e9conomiques et \u00e9tudes de march\u00e9<\/strong>Pour des raisons de gestion d'entreprise et afin de pouvoir identifier les tendances du march\u00e9, les souhaits des partenaires contractuels et des utilisateurs, nous analysons les donn\u00e9es dont nous disposons concernant les op\u00e9rations commerciales, les contrats, les demandes, etc., sachant que le groupe des personnes concern\u00e9es peut comprendre les partenaires contractuels, les personnes int\u00e9ress\u00e9es, les clients, les visiteurs et les utilisateurs de notre offre en ligne.<\/p>\n\n\n\n<p>Les analyses sont effectu\u00e9es \u00e0 des fins d'\u00e9valuation \u00e9conomique, de marketing et d'\u00e9tude de march\u00e9 (par ex. pour d\u00e9terminer des groupes de clients aux caract\u00e9ristiques diff\u00e9rentes). Dans ce cadre, nous pouvons prendre en compte les profils des utilisateurs enregistr\u00e9s, y compris leurs donn\u00e9es, par exemple les prestations utilis\u00e9es. Les analyses ne servent qu'\u00e0 nous et ne sont pas divulgu\u00e9es \u00e0 l'ext\u00e9rieur, sauf s'il s'agit d'analyses anonymes avec des valeurs regroup\u00e9es, donc anonymes. En outre, nous respectons la vie priv\u00e9e des utilisateurs et traitons les donn\u00e9es \u00e0 des fins d'analyse de mani\u00e8re aussi pseudonyme que possible et, dans la mesure du possible, anonyme (par ex. sous forme de donn\u00e9es agr\u00e9g\u00e9es).<\/p>\n\n\n\n<p><strong>Boutique et e-commerce<\/strong>Nous traitons les donn\u00e9es de nos clients afin de leur permettre de choisir, d'acheter ou de commander les produits, marchandises et services associ\u00e9s s\u00e9lectionn\u00e9s, ainsi que de les payer et de les livrer ou de les ex\u00e9cuter. Si l'ex\u00e9cution d'une commande l'exige, nous faisons appel \u00e0 des prestataires de services, en particulier \u00e0 des entreprises postales, de transport et d'exp\u00e9dition, pour effectuer la livraison ou l'ex\u00e9cution vis-\u00e0-vis de nos clients. Pour le traitement des op\u00e9rations de paiement, nous faisons appel aux services de banques et de prestataires de services de paiement. Les informations requises sont indiqu\u00e9es en tant que telles dans le cadre de la commande ou du processus d'achat comparable et comprennent les informations n\u00e9cessaires \u00e0 la livraison, ou \u00e0 la mise \u00e0 disposition et \u00e0 la facturation, ainsi que des informations de contact pour pouvoir \u00e9ventuellement se concerter.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'inventaire (p. ex. noms, adresses), donn\u00e9es de paiement (p. ex. coordonn\u00e9es bancaires, factures, historique des paiements), donn\u00e9es de contact (p. ex. e-mail, num\u00e9ros de t\u00e9l\u00e9phone), donn\u00e9es contractuelles (p. ex. objet du contrat, dur\u00e9e, cat\u00e9gorie de clients), donn\u00e9es d'utilisation (p. ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (p. ex. informations sur les appareils, adresses IP).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> prospects, partenaires commerciaux et contractuels, clients.<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> Fourniture de prestations contractuelles et service \u00e0 la client\u00e8le, demandes de contact et communication, proc\u00e9dures de bureau et d'organisation, gestion et r\u00e9ponse aux demandes, mesures de s\u00e9curit\u00e9, \u00e9valuation des actions de visite, marketing bas\u00e9 sur les int\u00e9r\u00eats et le comportement, profilage (cr\u00e9ation de profils d'utilisateurs).<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Ex\u00e9cution du contrat et demandes pr\u00e9contractuelles (art. 6, paragraphe 1, phrase 1, point b) du RGPD), obligation l\u00e9gale (art. 6, paragraphe 1, phrase 1, point c) du RGPD), int\u00e9r\u00eats l\u00e9gitimes (art. 6, paragraphe 1, phrase 1, point f) du RGPD).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m326\">Prestataire de services de paiement<\/h2>\n\n\n\n<p>Dans le cadre de relations contractuelles et d'autres relations juridiques, en raison d'obligations l\u00e9gales ou autrement sur la base de nos int\u00e9r\u00eats l\u00e9gitimes, nous proposons aux personnes concern\u00e9es des possibilit\u00e9s de paiement efficaces et s\u00fbres et faisons appel \u00e0 cet effet, outre aux banques et aux \u00e9tablissements de cr\u00e9dit, \u00e0 d'autres prestataires de services de paiement (collectivement, les \u201eprestataires de services de paiement\u201c).<\/p>\n\n\n\n<p>Les donn\u00e9es trait\u00e9es par les prestataires de services de paiement comprennent les donn\u00e9es d'inventaire, telles que le nom et l'adresse, les donn\u00e9es bancaires, telles que les num\u00e9ros de compte ou de carte de cr\u00e9dit, les mots de passe, les num\u00e9ros TAN et les sommes de contr\u00f4le, ainsi que les informations relatives au contrat, aux totaux et aux b\u00e9n\u00e9ficiaires. Ces informations sont n\u00e9cessaires pour effectuer les transactions. Les donn\u00e9es saisies ne sont toutefois trait\u00e9es que par les prestataires de services de paiement et stock\u00e9es chez eux. En d'autres termes, nous ne recevons pas d'informations relatives au compte ou \u00e0 la carte de cr\u00e9dit, mais uniquement des informations avec confirmation ou non du paiement. Dans certaines circonstances, les donn\u00e9es sont transmises par les prestataires de services de paiement \u00e0 des agences d'\u00e9valuation du cr\u00e9dit. Cette transmission a pour but de v\u00e9rifier l'identit\u00e9 et la solvabilit\u00e9. Nous renvoyons \u00e0 ce sujet aux conditions g\u00e9n\u00e9rales et aux informations sur la protection des donn\u00e9es des prestataires de services de paiement.<\/p>\n\n\n\n<p>Les op\u00e9rations de paiement sont soumises aux conditions g\u00e9n\u00e9rales et aux informations relatives \u00e0 la protection des donn\u00e9es des prestataires de services de paiement respectifs, qui peuvent \u00eatre consult\u00e9es sur les sites web ou les applications de transaction correspondants. Nous y renvoyons \u00e9galement pour de plus amples informations et pour faire valoir les droits de r\u00e9vocation, d'information et autres droits des personnes concern\u00e9es.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'inventaire (p. ex. noms, adresses), donn\u00e9es de paiement (p. ex. coordonn\u00e9es bancaires, factures, historique des paiements), donn\u00e9es contractuelles (p. ex. objet du contrat, dur\u00e9e, cat\u00e9gorie de clients), donn\u00e9es d'utilisation (p. ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (p. ex. informations sur les appareils, adresses IP).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Clients, prospects.<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> Fourniture de prestations contractuelles et service \u00e0 la client\u00e8le.<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Ex\u00e9cution du contrat et demandes pr\u00e9contractuelles (article 6, paragraphe 1, phrase 1, point b) du RGPD), int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f) du RGPD).<\/li>\n<\/ul>\n\n\n\n<p><strong>Services utilis\u00e9s et fournisseurs de services :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>PayPal :<\/strong> Services et solutions de paiement (p. ex. PayPal, PayPal Plus, Braintree) ; fournisseur de services : PayPal (Europe) S.\u00e0 r.l. et Cie, S.C.A., 22-24 Boulevard Royal, L-2449 Luxembourg ; site web : <a href=\"https:\/\/www.paypal.com\/de\" target=\"_blank\" rel=\"noopener\">https:\/\/www.paypal.com\/de<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full\" target=\"_blank\" rel=\"noopener\">https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m325\">Mise \u00e0 disposition de l'offre en ligne et h\u00e9bergement web<\/h2>\n\n\n\n<p>Afin de pouvoir mettre \u00e0 disposition notre offre en ligne de mani\u00e8re s\u00fbre et efficace, nous faisons appel aux services d'un ou de plusieurs fournisseurs d'h\u00e9bergement web, dont les serveurs (ou les serveurs g\u00e9r\u00e9s par eux) permettent d'acc\u00e9der \u00e0 l'offre en ligne. \u00c0 ces fins, nous pouvons faire appel \u00e0 des services d'infrastructure et de plateforme, \u00e0 une capacit\u00e9 de calcul, \u00e0 un espace de stockage et \u00e0 des services de base de donn\u00e9es ainsi qu'\u00e0 des services de s\u00e9curit\u00e9 et de maintenance technique.<\/p>\n\n\n\n<p>Les donn\u00e9es trait\u00e9es dans le cadre de la mise \u00e0 disposition de l'offre d'h\u00e9bergement peuvent comprendre toutes les donn\u00e9es concernant les utilisateurs de notre offre en ligne, qui sont g\u00e9n\u00e9r\u00e9es dans le cadre de l'utilisation et de la communication. En font r\u00e9guli\u00e8rement partie l'adresse IP, qui est n\u00e9cessaire pour pouvoir livrer les contenus des offres en ligne aux navigateurs, et toutes les saisies effectu\u00e9es dans le cadre de notre offre en ligne ou de pages web.<\/p>\n\n\n\n<p><strong>Envoi et h\u00e9bergement d'e-mails<\/strong>Les services d'h\u00e9bergement que nous utilisons comprennent \u00e9galement l'envoi, la r\u00e9ception et le stockage d'e-mails. \u00c0 ces fins, les adresses des destinataires et des exp\u00e9diteurs ainsi que d'autres informations concernant l'envoi d'e-mails (par ex. les fournisseurs d'acc\u00e8s concern\u00e9s) et le contenu des e-mails respectifs sont trait\u00e9s. Les donn\u00e9es susmentionn\u00e9es peuvent \u00e9galement \u00eatre trait\u00e9es \u00e0 des fins de d\u00e9tection des SPAM. Nous vous prions de noter que les e-mails envoy\u00e9s sur Internet ne sont en principe pas crypt\u00e9s. En r\u00e8gle g\u00e9n\u00e9rale, les e-mails sont certes crypt\u00e9s lors du transport, mais pas sur les serveurs d'o\u00f9 ils sont envoy\u00e9s et re\u00e7us (dans la mesure o\u00f9 aucune proc\u00e9dure de cryptage de bout en bout n'est utilis\u00e9e). Nous ne pouvons donc pas assumer la responsabilit\u00e9 de la voie de transmission des e-mails entre l'exp\u00e9diteur et la r\u00e9ception sur notre serveur.<\/p>\n\n\n\n<p><strong>Collecte des donn\u00e9es d'acc\u00e8s et des fichiers journaux<\/strong>Nous-m\u00eames (ou notre fournisseur d'h\u00e9bergement) collectons des donn\u00e9es pour chaque acc\u00e8s au serveur (appel\u00e9es fichiers journaux du serveur). Les fichiers journaux du serveur peuvent comprendre l'adresse et le nom des pages web et des fichiers consult\u00e9s, la date et l'heure de la consultation, les quantit\u00e9s de donn\u00e9es transmises, la notification de la r\u00e9ussite de la consultation, le type de navigateur et sa version, le syst\u00e8me d'exploitation de l'utilisateur, l'URL de r\u00e9f\u00e9rence (la page visit\u00e9e pr\u00e9c\u00e9demment) et, en r\u00e8gle g\u00e9n\u00e9rale, les adresses IP et le fournisseur d'acc\u00e8s.<\/p>\n\n\n\n<p>Les fichiers journaux du serveur peuvent \u00eatre utilis\u00e9s, d'une part, \u00e0 des fins de s\u00e9curit\u00e9, par exemple pour \u00e9viter une surcharge des serveurs (notamment en cas d'attaques abusives, dites attaques DDoS) et, d'autre part, pour garantir la charge des serveurs et leur stabilit\u00e9.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es de contenu (par ex. entr\u00e9es dans des formulaires en ligne), donn\u00e9es d'utilisation (par ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (par ex. informations sur les appareils, adresses IP).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Utilisateurs (par exemple, visiteurs de sites web, utilisateurs de services en ligne).<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f. du RGPD).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m182\">Prise de contact<\/h2>\n\n\n\n<p>Lorsque vous nous contactez (par ex. par formulaire de contact, e-mail, t\u00e9l\u00e9phone ou via les m\u00e9dias sociaux), nous traitons les donn\u00e9es des personnes qui nous contactent, dans la mesure o\u00f9 cela est n\u00e9cessaire pour r\u00e9pondre aux demandes de contact et aux \u00e9ventuelles mesures demand\u00e9es.<\/p>\n\n\n\n<p>La r\u00e9ponse aux demandes de contact dans le cadre de relations contractuelles ou pr\u00e9contractuelles a lieu pour remplir nos obligations contractuelles ou pour r\u00e9pondre \u00e0 des demandes (pr\u00e9)contractuelles et, par ailleurs, sur la base des int\u00e9r\u00eats l\u00e9gitimes \u00e0 r\u00e9pondre aux demandes.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'inventaire (p. ex. noms, adresses), donn\u00e9es de contact (p. ex. e-mail, num\u00e9ros de t\u00e9l\u00e9phone), donn\u00e9es de contenu (p. ex. saisies dans des formulaires en ligne), donn\u00e9es d'utilisation (p. ex. pages web visit\u00e9es, int\u00e9r\u00eat pour le contenu, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (p. ex. informations sur les appareils, adresses IP).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Partenaires de communication, personnes int\u00e9ress\u00e9es.<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> Demandes de contact et communication, gestion et r\u00e9ponse aux demandes.<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Ex\u00e9cution du contrat et demandes pr\u00e9contractuelles (article 6, paragraphe 1, phrase 1, point b) du RGPD), int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f) du RGPD).<\/li>\n<\/ul>\n\n\n\n<p><strong>Services utilis\u00e9s et fournisseurs de services :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Formulaire de contact : <\/strong>Lorsque les utilisateurs nous contactent via notre formulaire de contact, par e-mail ou par d'autres moyens de communication, nous traitons les donn\u00e9es qui nous sont communiqu\u00e9es dans ce contexte afin de traiter la demande communiqu\u00e9e. \u00c0 cette fin, nous traitons les donn\u00e9es \u00e0 caract\u00e8re personnel dans le cadre de relations commerciales pr\u00e9contractuelles et contractuelles, dans la mesure o\u00f9 cela est n\u00e9cessaire \u00e0 leur ex\u00e9cution et, par ailleurs, sur la base de nos int\u00e9r\u00eats l\u00e9gitimes ainsi que des int\u00e9r\u00eats des partenaires de communication \u00e0 r\u00e9pondre aux demandes et de nos obligations l\u00e9gales de conservation.<\/li>\n\n\n\n<li><strong>Help Scout :<\/strong> Gestion des demandes de contact et des communications ; fournisseur de services : Help Scout Inc, 131 Tremont St, Boston, MA 02111-1338, \u00c9tats-Unis ; site web : <a href=\"https:\/\/www.helpscout.net\" target=\"_blank\" rel=\"noopener\">https:\/\/www.helpscout.net<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/www.helpscout.net\/company\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.helpscout.net\/company\/legal\/privacy\/<\/a>; Base du transfert vers un pays tiers : clauses contractuelles types (<a href=\"https:\/\/www.helpscout.com\/company\/legal\/dpa\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.helpscout.com\/company\/legal\/dpa\/<\/a>) ; contrat de traitement des commandes : <a href=\"https:\/\/www.helpscout.com\/company\/legal\/dpa\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.helpscout.com\/company\/legal\/dpa\/<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m17\">Bulletins d'information et notifications \u00e9lectroniques<\/h2>\n\n\n\n<p>Nous n'envoyons des newsletters, des e-mails et d'autres notifications \u00e9lectroniques (ci-apr\u00e8s \u201enewsletter\u201c) qu'avec le consentement des destinataires ou une autorisation l\u00e9gale. Dans la mesure o\u00f9, dans le cadre d'une inscription \u00e0 la newsletter, son contenu est concr\u00e8tement d\u00e9crit, il est d\u00e9terminant pour le consentement des utilisateurs. Par ailleurs, nos newsletters contiennent des informations sur nos prestations et sur nous-m\u00eames.<\/p>\n\n\n\n<p>Pour vous abonner \u00e0 nos newsletters, il vous suffit en principe d'indiquer votre adresse e-mail. Nous pouvons toutefois vous demander d'indiquer un nom, afin de vous adresser personnellement \u00e0 vous dans la newsletter, ou d'autres informations, dans la mesure o\u00f9 elles sont n\u00e9cessaires aux fins de la newsletter.<\/p>\n\n\n\n<p><strong>Proc\u00e9dure de double opt-in :<\/strong> L'inscription \u00e0 notre newsletter se fait en principe dans le cadre d'une proc\u00e9dure dite de double opt-in. Cela signifie qu'apr\u00e8s l'inscription, vous recevez un e-mail vous demandant de confirmer votre inscription. Cette confirmation est n\u00e9cessaire pour que personne ne puisse s'inscrire avec des adresses e-mail \u00e9trang\u00e8res. Les inscriptions \u00e0 la newsletter sont enregistr\u00e9es afin de pouvoir prouver le processus d'inscription conform\u00e9ment aux exigences l\u00e9gales. Cela comprend l'enregistrement de l'heure d'inscription et de confirmation ainsi que de l'adresse IP. De m\u00eame, les modifications de vos donn\u00e9es enregistr\u00e9es aupr\u00e8s du prestataire de services d'envoi sont consign\u00e9es.<\/p>\n\n\n\n<p><strong>l'effacement et la limitation du traitement : <\/strong> Nous pouvons conserver les adresses \u00e9lectroniques d\u00e9sinscrites jusqu'\u00e0 trois ans sur la base de nos int\u00e9r\u00eats l\u00e9gitimes, avant de les supprimer afin de pouvoir prouver un consentement pr\u00e9c\u00e9demment donn\u00e9. Le traitement de ces donn\u00e9es est limit\u00e9 aux fins d'une \u00e9ventuelle d\u00e9fense contre des r\u00e9clamations. Une demande individuelle d'effacement est possible \u00e0 tout moment, \u00e0 condition que l'existence d'un ancien consentement soit confirm\u00e9e. En cas d'obligation de respecter durablement les oppositions, nous nous r\u00e9servons le droit d'enregistrer l'adresse \u00e9lectronique dans une liste de blocage (dite \u201eliste noire\u201c), uniquement \u00e0 cette fin.<\/p>\n\n\n\n<p>L'enregistrement de la proc\u00e9dure d'inscription se fait sur la base de nos int\u00e9r\u00eats l\u00e9gitimes \u00e0 des fins de preuve de son bon d\u00e9roulement. Si nous chargeons un prestataire de services d'envoyer des e-mails, cela se fait sur la base de nos int\u00e9r\u00eats l\u00e9gitimes \u00e0 un syst\u00e8me d'envoi efficace et s\u00fbr.<\/p>\n\n\n\n<p><strong>Remarques sur les bases juridiques :<\/strong> L'envoi des newsletters se fait sur la base du consentement des destinataires ou, si un consentement n'est pas n\u00e9cessaire, sur la base de nos int\u00e9r\u00eats l\u00e9gitimes en mati\u00e8re de marketing direct, si et dans la mesure o\u00f9 cela est autoris\u00e9 par la loi, par exemple dans le cas de la prospection de clients existants. Si nous chargeons un prestataire de services d'envoyer des e-mails, nous le faisons sur la base de nos int\u00e9r\u00eats l\u00e9gitimes. La proc\u00e9dure d'enregistrement est enregistr\u00e9e sur la base de nos int\u00e9r\u00eats l\u00e9gitimes afin de d\u00e9montrer qu'elle a \u00e9t\u00e9 effectu\u00e9e conform\u00e9ment \u00e0 la loi.<\/p>\n\n\n\n<p><strong>Contenu :<\/strong> Informations sur nous, nos services, nos actions et nos offres.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'inventaire (p. ex. noms, adresses), donn\u00e9es de contact (p. ex. e-mail, num\u00e9ros de t\u00e9l\u00e9phone), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (p. ex. informations sur les appareils, adresses IP), donn\u00e9es d'utilisation (p. ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Partenaires de communication.<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> le marketing direct (par exemple, par courrier \u00e9lectronique ou postal).<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Consentement (art. 6, paragraphe 1, phrase 1, point a. RGPD), Int\u00e9r\u00eats l\u00e9gitimes (art. 6, paragraphe 1, phrase 1, point f. RGPD).<\/li>\n\n\n\n<li><strong>Possibilit\u00e9 de s'y opposer (opt-out) :<\/strong> Vous pouvez \u00e0 tout moment r\u00e9silier la r\u00e9ception de notre newsletter, c'est-\u00e0-dire r\u00e9voquer vos consentements ou vous opposer \u00e0 la poursuite de la r\u00e9ception. Vous trouverez un lien pour vous d\u00e9sabonner de la newsletter \u00e0 la fin de chaque newsletter ou vous pouvez utiliser l'une des possibilit\u00e9s de contact indiqu\u00e9es ci-dessus, de pr\u00e9f\u00e9rence par e-mail.<\/li>\n<\/ul>\n\n\n\n<p><strong>Services utilis\u00e9s et fournisseurs de services :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Mesure des taux d'ouverture et de clics : <\/strong>Les newsletters contiennent ce que l'on appelle un \u201epixel invisible\u201c, c'est-\u00e0-dire un fichier de la taille d'un pixel qui, \u00e0 l'ouverture de la newsletter, est appel\u00e9 par notre serveur ou par son serveur si nous faisons appel \u00e0 un prestataire de services d'exp\u00e9dition. Dans le cadre de cet appel, des informations techniques, comme par exemple des indications sur le navigateur et votre syst\u00e8me, ainsi que votre adresse IP et l'heure de l'appel sont d'abord collect\u00e9es. Ces informations sont utilis\u00e9es pour l'am\u00e9lioration technique de notre newsletter \u00e0 l'aide des donn\u00e9es techniques ou des groupes cibles et de leur comportement de lecture sur la base de leur lieu de consultation (qui peut \u00eatre d\u00e9termin\u00e9 \u00e0 l'aide de l'adresse IP) ou des heures d'acc\u00e8s. Cette analyse consiste \u00e9galement \u00e0 d\u00e9terminer si et quand les newsletters sont ouvertes et quels liens sont cliqu\u00e9s. Les informations sont attribu\u00e9es aux diff\u00e9rents destinataires de la newsletter et enregistr\u00e9es dans leurs profils jusqu'\u00e0 leur suppression. Ces analyses nous permettent de conna\u00eetre les habitudes de lecture de nos utilisateurs et d'adapter nos contenus \u00e0 ces derniers ou d'envoyer des contenus diff\u00e9rents en fonction des int\u00e9r\u00eats de nos utilisateurs. La mesure des taux d'ouverture et de clics ainsi que l'enregistrement des r\u00e9sultats de mesure dans les profils des utilisateurs et leur traitement ult\u00e9rieur sont effectu\u00e9s sur la base d'un consentement des utilisateurs. Une r\u00e9vocation s\u00e9par\u00e9e de la mesure du succ\u00e8s n'est malheureusement pas possible, dans ce cas, l'abonnement complet \u00e0 la newsletter doit \u00eatre r\u00e9sili\u00e9 ou contredit. Dans ce cas, les informations de profil enregistr\u00e9es seront supprim\u00e9es ; <span class=\"prev_lb_wrp\"><strong>Bases juridiques :<\/strong> Consentement (article 6, paragraphe 1, phrase 1, point a) du RGPD) ;<\/span><\/li>\n\n\n\n<li><strong>CleverReach :<\/strong> Plate-forme de marketing par courriel ; fournisseur de services : CleverReach GmbH &amp; Co. KG, \/\/CRASH Building, Schafj\u00fcckenweg 2, 26180 Rastede, Allemagne ; Site web : <a href=\"https:\/\/www.cleverreach.com\/de\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cleverreach.com\/de<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/www.cleverreach.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cleverreach.com\/de\/datenschutz\/<\/a>; Contrat de traitement des commandes : conclu avec le fournisseur.<\/li>\n\n\n\n<li><strong>Mailchimp : <\/strong>Plate-forme d'envoi d'e-mails et de marketing par e-mail ; fournisseur de services : Rocket Science Group, LLC, 675 Ponce De Leon Ave NE #5000, Atlanta, GA 30308, \u00c9tats-Unis ; site web : <a href=\"https:\/\/mailchimp.com\" target=\"_blank\" rel=\"noopener\">https:\/\/mailchimp.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/mailchimp.com\/legal\/\" target=\"_blank\" rel=\"noopener\">https:\/\/mailchimp.com\/legal\/<\/a>; contrat de traitement des commandes : <a href=\"https:\/\/mailchimp.com\/legal\/\" target=\"_blank\" rel=\"noopener\">https:\/\/mailchimp.com\/legal\/<\/a>; Base du transfert vers un pays tiers : Data Privacy Framework, clauses contractuelles standard (inclusion dans le contrat de sous-traitance) ; Autres informations : Mesures de s\u00e9curit\u00e9 particuli\u00e8res : <a href=\"https:\/\/mailchimp.com\/help\/Mailchimp-european-data-transfers\/\" target=\"_blank\" rel=\"noopener\">https:\/\/mailchimp.com\/help\/Mailchimp-european-data-transfers\/<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m263\">Analyse web, suivi et optimisation<\/h2>\n\n\n\n<p>L'analyse web (\u00e9galement appel\u00e9e \u201emesure d'audience\u201c) sert \u00e0 \u00e9valuer les flux de visiteurs de notre offre en ligne et peut comprendre le comportement, les int\u00e9r\u00eats ou les informations d\u00e9mographiques des visiteurs, comme l'\u00e2ge ou le sexe, sous forme de valeurs pseudonymes. L'analyse de la port\u00e9e nous permet par exemple de savoir \u00e0 quel moment notre offre en ligne ou ses fonctions ou contenus sont le plus souvent utilis\u00e9s ou invitent \u00e0 les r\u00e9utiliser. De m\u00eame, nous pouvons comprendre quels sont les domaines qui n\u00e9cessitent une optimisation.<\/p>\n\n\n\n<p>Outre l'analyse web, nous pouvons \u00e9galement utiliser des proc\u00e9dures de test, par exemple pour tester et optimiser diff\u00e9rentes versions de notre offre en ligne ou de ses composants.<\/p>\n\n\n\n<p>\u00c0 ces fins, des profils d'utilisateurs peuvent \u00eatre cr\u00e9\u00e9s et enregistr\u00e9s dans un fichier (appel\u00e9 \u201ecookie\u201c) ou des proc\u00e9dures similaires peuvent \u00eatre utilis\u00e9es dans le m\u00eame but. Ces donn\u00e9es peuvent inclure, par exemple, les contenus consult\u00e9s, les pages web visit\u00e9es et les \u00e9l\u00e9ments qui y sont utilis\u00e9s, ainsi que des informations techniques telles que le navigateur utilis\u00e9, le syst\u00e8me informatique utilis\u00e9 et des informations sur les heures d'utilisation. Si les utilisateurs ont consenti \u00e0 la collecte de leurs donn\u00e9es de localisation, celles-ci peuvent \u00e9galement \u00eatre trait\u00e9es selon le fournisseur.<\/p>\n\n\n\n<p>Les adresses IP des utilisateurs sont \u00e9galement collect\u00e9es. Toutefois, nous utilisons un proc\u00e9d\u00e9 de masquage IP (c'est-\u00e0-dire une pseudonymisation par raccourcissement de l'adresse IP) pour prot\u00e9ger les utilisateurs. En g\u00e9n\u00e9ral, les donn\u00e9es claires des utilisateurs (telles que les adresses e-mail ou les noms) ne sont pas enregistr\u00e9es dans le cadre de l'analyse web, des tests A\/B et de l'optimisation, mais sous forme de pseudonymes. Cela signifie que nous, ainsi que les fournisseurs des logiciels utilis\u00e9s, ne connaissons pas l'identit\u00e9 r\u00e9elle des utilisateurs, mais uniquement les donn\u00e9es enregistr\u00e9es dans leurs profils aux fins des proc\u00e9dures respectives.<\/p>\n\n\n\n<p><strong>Remarques sur les bases juridiques :<\/strong> Dans la mesure o\u00f9 nous demandons aux utilisateurs de consentir \u00e0 l'utilisation des fournisseurs tiers, la base juridique du traitement des donn\u00e9es est le consentement. Dans le cas contraire, les donn\u00e9es des utilisateurs sont trait\u00e9es sur la base de nos int\u00e9r\u00eats l\u00e9gitimes (c'est-\u00e0-dire l'int\u00e9r\u00eat \u00e0 fournir des services efficaces, \u00e9conomiques et adapt\u00e9s aux besoins des destinataires). Dans ce contexte, nous souhaitons \u00e9galement attirer votre attention sur les informations relatives \u00e0 l'utilisation des cookies dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'utilisation (par ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (par ex. informations sur les appareils, adresses IP).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Utilisateurs (par exemple, visiteurs de sites web, utilisateurs de services en ligne).<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> Mesure de la port\u00e9e (par ex. statistiques d'acc\u00e8s, reconnaissance des visiteurs r\u00e9currents), tracking (par ex. profilage bas\u00e9 sur les int\u00e9r\u00eats\/le comportement, utilisation de cookies), \u00e9valuation des actions de visite, profilage (cr\u00e9ation de profils d'utilisateurs).<\/li>\n\n\n\n<li><strong>Mesures de s\u00e9curit\u00e9 :<\/strong> Masquage IP (pseudonymisation de l'adresse IP).<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Consentement (art. 6, paragraphe 1, phrase 1, point a. RGPD), Int\u00e9r\u00eats l\u00e9gitimes (art. 6, paragraphe 1, phrase 1, point f. RGPD).<\/li>\n<\/ul>\n\n\n\n<p><strong>Services utilis\u00e9s et fournisseurs de services :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Google Analytics : <\/strong>Nous utilisons Google Analytics pour mesurer et analyser l'utilisation de notre offre en ligne sur la base d'un num\u00e9ro d'identification d'utilisateur pseudonyme. Ce num\u00e9ro d'identification ne contient aucune donn\u00e9e univoque, comme un nom ou une adresse e-mail. Il sert \u00e0 attribuer des informations d'analyse \u00e0 un terminal afin de reconna\u00eetre les contenus que les utilisateurs ont consult\u00e9s au cours d'une ou de plusieurs utilisations, les termes de recherche qu'ils ont utilis\u00e9s, qu'ils ont consult\u00e9s \u00e0 nouveau ou qu'ils ont interagi avec notre offre en ligne. De m\u00eame, le moment de l'utilisation et sa dur\u00e9e sont enregistr\u00e9s, ainsi que les sources des utilisateurs qui renvoient \u00e0 notre offre en ligne et les aspects techniques de leurs terminaux et navigateurs.<br>Pour ce faire, des profils pseudonymes d'utilisateurs sont cr\u00e9\u00e9s \u00e0 l'aide d'informations provenant de l'utilisation de diff\u00e9rents appareils, des cookies pouvant \u00eatre utilis\u00e9s. Google Analytics ne consigne pas et ne stocke pas les adresses IP individuelles pour les utilisateurs de l'UE. Toutefois, Analytics fournit des donn\u00e9es de localisation g\u00e9ographique approximatives en d\u00e9rivant les m\u00e9tadonn\u00e9es suivantes des adresses IP : Ville (et la latitude et la longitude d\u00e9riv\u00e9es de la ville), continent, pays, r\u00e9gion, sous-continent (et contreparties bas\u00e9es sur l'ID). Pour le trafic de l'UE, les donn\u00e9es d'adresse IP sont utilis\u00e9es exclusivement pour cette d\u00e9rivation des donn\u00e9es de g\u00e9olocalisation avant d'\u00eatre imm\u00e9diatement supprim\u00e9es. Elles ne sont pas consign\u00e9es, ne sont pas accessibles et ne sont pas utilis\u00e9es \u00e0 d'autres fins. Lorsque Google Analytics collecte des donn\u00e9es de mesure, toutes les requ\u00eates IP sont effectu\u00e9es sur des serveurs bas\u00e9s dans l'UE avant que le trafic ne soit transf\u00e9r\u00e9 aux serveurs d'Analytics pour traitement ; fournisseur de services : Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : consentement (article 6, paragraphe 1, phrase 1, point a) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/marketingplatform.google.com\/intl\/de\/about\/analytics\/\" target=\"_blank\" rel=\"noopener\">https:\/\/marketingplatform.google.com\/intl\/de\/about\/analytics\/<\/a>; Mesures de s\u00e9curit\u00e9 : Masquage IP (pseudonymisation de l'adresse IP) ; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>; contrat de traitement des commandes : <a href=\"https:\/\/business.safety.google\/adsprocessorterms\/\" target=\"_blank\" rel=\"noopener\">https:\/\/business.safety.google\/adsprocessorterms\/<\/a>; base des transferts vers des pays tiers : Data Privacy Framework (DPF) ; possibilit\u00e9 d'opposition (opt-out) : Plugin d'opt-out : <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>, param\u00e8tres d'affichage des publicit\u00e9s : <a href=\"https:\/\/myadcenter.google.com\/personalizationoff\" target=\"_blank\" rel=\"noopener\">https:\/\/myadcenter.google.com\/personalizationoff<\/a>; Autres informations : <a href=\"https:\/\/business.safety.google\/adsservices\/\" target=\"_blank\" rel=\"noopener\">https:\/\/business.safety.google\/adsservices\/<\/a> (types de traitement ainsi que les donn\u00e9es trait\u00e9es).<\/li>\n\n\n\n<li><strong>Google en tant que destinataire du consentement : <\/strong>Le consentement donn\u00e9 par les utilisateurs dans le cadre d'un dialogue de consentement (\u00e9galement connu sous le nom de \u201ecookie opt-in\/consentement\u201c, \u201abanni\u00e8re de cookie\u2018, etc.) remplit plusieurs objectifs. D'une part, il nous sert \u00e0 remplir notre obligation d'obtenir un consentement pour le stockage et la lecture d'informations sur et \u00e0 partir de l'\u00e9quipement terminal des utilisateurs (conform\u00e9ment aux directives ePrivacy). D'autre part, il couvre le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel des utilisateurs conform\u00e9ment aux exigences en mati\u00e8re de protection des donn\u00e9es. En outre, ce consentement s'applique \u00e9galement \u00e0 Google, puisque l'entreprise est tenue, en vertu de la loi sur les march\u00e9s num\u00e9riques, d'obtenir un consentement pour les services personnalis\u00e9s. Nous partageons donc avec Google le statut des consentements donn\u00e9s par les utilisateurs. Notre logiciel de gestion des consentements informe Google si des consentements ont \u00e9t\u00e9 accord\u00e9s ou non. L'objectif est de garantir que les consentements donn\u00e9s ou non par les utilisateurs sont pris en compte lors de l'utilisation de Google Analytics et de l'int\u00e9gration de fonctionnalit\u00e9s et de services externes. Ainsi, les consentements des utilisateurs et leur retrait dans le cadre de Google Analytics et d'autres services Google peuvent \u00eatre adapt\u00e9s de mani\u00e8re dynamique dans notre offre en ligne, en fonction des choix des utilisateurs ; <strong>Fournisseur de services :<\/strong> Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande ; <span class=\"prev_lb_wrp\"><strong>Bases juridiques :<\/strong> Consentement (article 6, paragraphe 1, phrase 1, point a) du RGPD) ; <\/span><strong>Site web :<\/strong> <a href=\"https:\/\/support.google.com\/analytics\/answer\/9976101?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/support.google.com\/analytics\/answer\/9976101?hl=de<\/a>; <strong>D\u00e9claration de confidentialit\u00e9 :<\/strong> <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>.<\/li>\n\n\n\n<li><strong>Google Tag Manager :<\/strong> Google Tag Manager est une solution qui nous permet de g\u00e9rer les balises de site web via une interface et d'int\u00e9grer ainsi d'autres services dans notre offre en ligne (nous renvoyons \u00e0 ce sujet \u00e0 d'autres informations dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9). Le Tag Manager lui-m\u00eame (qui impl\u00e9mente les balises) ne cr\u00e9e donc pas encore de profils d'utilisateurs et n'enregistre pas de cookies. Google apprend uniquement l'adresse IP de l'utilisateur, ce qui est n\u00e9cessaire pour ex\u00e9cuter le Google Tag Manager ; fournisseur de services : Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande, soci\u00e9t\u00e9 m\u00e8re : Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, \u00c9tats-Unis ; site web : <a href=\"https:\/\/marketingplatform.google.com\" target=\"_blank\" rel=\"noopener\">https:\/\/marketingplatform.google.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>; contrat de traitement des commandes :<br><a href=\"https:\/\/business.safety.google\/adsprocessorterms\" target=\"_blank\" rel=\"noopener\">https:\/\/business.safety.google\/adsprocessorterms<\/a>; Base du transfert vers un pays tiers : Data Privacy Framework, clauses contractuelles types (<a href=\"https:\/\/business.safety.google\/adsprocessorterms\" target=\"_blank\" rel=\"noopener\">https:\/\/business.safety.google\/adsprocessorterms<\/a>) ; informations compl\u00e9mentaires : <a href=\"https:\/\/privacy.google.com\/businesses\/adsservices\" target=\"_blank\" rel=\"noopener\">https:\/\/privacy.google.com\/businesses\/adsservices<\/a> (types de traitement ainsi que les donn\u00e9es trait\u00e9es).<\/li>\n\n\n\n<li><strong>Utilisation d'Independent Analytics<\/strong>Pour l'\u00e9valuation statistique de notre site web et l'am\u00e9lioration de l'exp\u00e9rience utilisateur, nous utilisons le logiciel \u201eIndependent Analytics\u201c. Cet outil conforme \u00e0 la protection des donn\u00e9es renonce totalement \u00e0 l'utilisation de cookies. Les donn\u00e9es collect\u00e9es (p. ex. nombre de pages vues, dur\u00e9e de la visite, sources d'origine) sont enregistr\u00e9es de mani\u00e8re purement locale sur notre serveur et imm\u00e9diatement rendues anonymes. Elles ne sont pas transmises \u00e0 des tiers ou \u00e0 des serveurs externes. Toute d\u00e9duction sur votre personne est donc exclue. Le traitement des donn\u00e9es se fonde sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 optimiser notre offre web conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point f du RGPD. \u00c9tant donn\u00e9 qu'aucune donn\u00e9e \u00e0 caract\u00e8re personnel n'est enregistr\u00e9e durablement, aucun consentement s\u00e9par\u00e9 n'est n\u00e9cessaire.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m264\">Marketing en ligne<\/h2>\n\n\n\n<p>Nous traitons les donn\u00e9es personnelles \u00e0 des fins de marketing en ligne, ce qui peut inclure, en particulier, la commercialisation d'espaces publicitaires ou la pr\u00e9sentation de contenus publicitaires et autres (collectivement d\u00e9nomm\u00e9s \u201econtenus\u201c) en fonction des int\u00e9r\u00eats potentiels des utilisateurs, ainsi que la mesure de leur efficacit\u00e9.<\/p>\n\n\n\n<p>\u00c0 ces fins, des profils d'utilisateurs sont cr\u00e9\u00e9s et enregistr\u00e9s dans un fichier (appel\u00e9 \u201ecookie\u201c) ou des proc\u00e9dures similaires sont utilis\u00e9es, au moyen desquelles les informations pertinentes sur l'utilisateur sont enregistr\u00e9es pour la pr\u00e9sentation des contenus susmentionn\u00e9s. Ces donn\u00e9es peuvent inclure, par exemple, les contenus consult\u00e9s, les pages web visit\u00e9es, les r\u00e9seaux en ligne utilis\u00e9s, mais aussi les partenaires de communication et les donn\u00e9es techniques, telles que le navigateur et le syst\u00e8me informatique utilis\u00e9s, ainsi que les donn\u00e9es relatives aux heures d'utilisation. Si les utilisateurs ont consenti \u00e0 la collecte de leurs donn\u00e9es de localisation, celles-ci peuvent \u00e9galement \u00eatre trait\u00e9es.<\/p>\n\n\n\n<p>Les adresses IP des utilisateurs sont \u00e9galement collect\u00e9es. Toutefois, nous utilisons les proc\u00e9dures de masquage IP disponibles (c'est-\u00e0-dire la pseudonymisation par raccourcissement de l'adresse IP) pour prot\u00e9ger les utilisateurs. En g\u00e9n\u00e9ral, dans le cadre de la proc\u00e9dure de marketing en ligne, aucune donn\u00e9e claire des utilisateurs (comme les adresses e-mail ou les noms) n'est enregistr\u00e9e, mais des pseudonymes. Cela signifie que nous, ainsi que les fournisseurs des proc\u00e9dures de marketing en ligne, ne connaissons pas l'identit\u00e9 r\u00e9elle des utilisateurs, mais uniquement les donn\u00e9es enregistr\u00e9es dans leurs profils.<\/p>\n\n\n\n<p>Les informations contenues dans les profils sont g\u00e9n\u00e9ralement enregistr\u00e9es dans des cookies ou par des proc\u00e9d\u00e9s similaires. Ces cookies peuvent \u00eatre lus ult\u00e9rieurement sur d'autres sites web qui utilisent le m\u00eame proc\u00e9d\u00e9 de marketing en ligne et \u00eatre analys\u00e9s \u00e0 des fins de pr\u00e9sentation de contenus ainsi que compl\u00e9t\u00e9s par d'autres donn\u00e9es et stock\u00e9s sur le serveur du fournisseur du proc\u00e9d\u00e9 de marketing en ligne.<\/p>\n\n\n\n<p>Exceptionnellement, des donn\u00e9es claires peuvent \u00eatre associ\u00e9es aux profils. C'est le cas, par exemple, lorsque les utilisateurs sont membres d'un r\u00e9seau social dont nous utilisons les proc\u00e9dures de marketing en ligne et que le r\u00e9seau associe les profils des utilisateurs aux donn\u00e9es susmentionn\u00e9es. Nous vous prions de noter que les utilisateurs peuvent conclure des accords suppl\u00e9mentaires avec les fournisseurs, par exemple en donnant leur consentement dans le cadre de l'enregistrement.<\/p>\n\n\n\n<p>En principe, nous n'avons acc\u00e8s qu'\u00e0 des informations globales sur le succ\u00e8s de nos annonces publicitaires. Toutefois, dans le cadre de ce que l'on appelle des mesures de conversion, nous pouvons v\u00e9rifier lesquelles de nos proc\u00e9dures de marketing en ligne ont conduit \u00e0 ce que l'on appelle une conversion, c'est-\u00e0-dire, par exemple, \u00e0 la conclusion d'un contrat avec nous. La mesure de la conversion est utilis\u00e9e uniquement pour analyser le succ\u00e8s de nos mesures de marketing.<\/p>\n\n\n\n<p>Sauf indication contraire, nous vous demandons de partir du principe que les cookies utilis\u00e9s sont conserv\u00e9s pendant une p\u00e9riode de deux ans.<\/p>\n\n\n\n<p><strong>Remarques sur les bases juridiques :<\/strong> Dans la mesure o\u00f9 nous demandons aux utilisateurs de consentir \u00e0 l'utilisation des fournisseurs tiers, la base juridique du traitement des donn\u00e9es est le consentement. Dans le cas contraire, les donn\u00e9es des utilisateurs sont trait\u00e9es sur la base de nos int\u00e9r\u00eats l\u00e9gitimes (c'est-\u00e0-dire l'int\u00e9r\u00eat \u00e0 fournir des services efficaces, \u00e9conomiques et adapt\u00e9s aux besoins des destinataires). Dans ce contexte, nous souhaitons \u00e9galement attirer votre attention sur les informations relatives \u00e0 l'utilisation des cookies dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'utilisation (par ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (par ex. informations sur les appareils, adresses IP), donn\u00e9es de localisation (indications sur la position g\u00e9ographique d'un appareil ou d'une personne).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Utilisateurs (par ex. visiteurs de sites web, utilisateurs de services en ligne), personnes int\u00e9ress\u00e9es.<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> Tracking (par ex. profilage bas\u00e9 sur les int\u00e9r\u00eats\/le comportement, utilisation de cookies), remarketing, \u00e9valuation des actions de visite, marketing bas\u00e9 sur les int\u00e9r\u00eats et le comportement, profilage (cr\u00e9ation de profils d'utilisateurs), mesure de la conversion (mesure de l'efficacit\u00e9 des mesures de marketing), mesure de la port\u00e9e (par ex. statistiques d'acc\u00e8s, identification des visiteurs r\u00e9currents), ciblage (d\u00e9termination de groupes cibles pertinents \u00e0 des fins de marketing ou autre \u00e9dition de contenus), cross-device tracking (traitement des donn\u00e9es des utilisateurs sur plusieurs appareils \u00e0 des fins de marketing).<\/li>\n\n\n\n<li><strong>Mesures de s\u00e9curit\u00e9 :<\/strong> Masquage IP (pseudonymisation de l'adresse IP).<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Consentement (art. 6, paragraphe 1, phrase 1, point a. RGPD), Int\u00e9r\u00eats l\u00e9gitimes (art. 6, paragraphe 1, phrase 1, point f. RGPD).<\/li>\n\n\n\n<li><strong>Possibilit\u00e9 de s'y opposer (opt-out) :<\/strong> Nous renvoyons aux informations sur la protection des donn\u00e9es des fournisseurs respectifs et aux possibilit\u00e9s d'opposition indiqu\u00e9es pour les fournisseurs (appel\u00e9es \u201eopt-out\u201c). Dans la mesure o\u00f9 aucune possibilit\u00e9 d'opt-out explicite n'a \u00e9t\u00e9 indiqu\u00e9e, vous avez d'une part la possibilit\u00e9 de d\u00e9sactiver les cookies dans les param\u00e8tres de votre navigateur. Cela peut toutefois limiter les fonctions de notre offre en ligne. Nous recommandons donc en outre les possibilit\u00e9s d'opt-out suivantes, qui sont propos\u00e9es en r\u00e9sum\u00e9 en fonction des r\u00e9gions respectives : a) Europe : <a href=\"https:\/\/www.youronlinechoices.eu\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youronlinechoices.eu<\/a>.<br>b) le Canada : <a href=\"https:\/\/www.youradchoices.ca\/choices\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youradchoices.ca\/choices<\/a>.<br>c) \u00c9tats-Unis : <a href=\"https:\/\/www.aboutads.info\/choices\" target=\"_blank\" rel=\"noopener\">https:\/\/www.aboutads.info\/choices<\/a>.<br>d) interr\u00e9gional : <a href=\"https:\/\/optout.aboutads.info\" target=\"_blank\" rel=\"noopener\">https:\/\/optout.aboutads.info<\/a>.<\/li>\n<\/ul>\n\n\n\n<p><strong>Services utilis\u00e9s et fournisseurs de services :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Google Ads et mesure de la conversion :<\/strong> Proc\u00e9dures de marketing en ligne dans le but de placer des contenus et des annonces au sein du r\u00e9seau publicitaire du fournisseur de services (par exemple, dans les r\u00e9sultats de recherche, dans des vid\u00e9os, sur des pages web, etc.) de mani\u00e8re \u00e0 ce qu'ils soient affich\u00e9s aux utilisateurs qui sont suppos\u00e9s \u00eatre int\u00e9ress\u00e9s par les annonces. En outre, nous mesurons la conversion des annonces, c'est-\u00e0-dire si les utilisateurs en ont profit\u00e9 pour interagir avec les annonces et utiliser les offres promues (ce que l'on appelle les conversions). Nous ne recevons toutefois que des informations anonymes et aucune information personnelle sur des utilisateurs individuels ; fournisseur de services : Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : consentement (art. 6, paragraphe 1, phrase 1, point a) du RGPD), int\u00e9r\u00eats l\u00e9gitimes (art. 6, paragraphe 1, phrase 1, point f) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/marketingplatform.google.com\" target=\"_blank\" rel=\"noopener\">https:\/\/marketingplatform.google.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>; Base des transferts vers des pays tiers : Data Privacy Framework (DPF) ; Autres informations : Types de traitement ainsi que les donn\u00e9es trait\u00e9es : <a href=\"https:\/\/business.safety.google\/adsservices\/\" target=\"_blank\" rel=\"noopener\">https:\/\/business.safety.google\/adsservices\/<\/a>; conditions de traitement des donn\u00e9es entre responsables et clauses contractuelles types pour les transferts de donn\u00e9es vers des pays tiers : <a href=\"https:\/\/business.safety.google\/adscontrollerterms\" target=\"_blank\" rel=\"noopener\">https:\/\/business.safety.google\/adscontrollerterms<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m136\">Pr\u00e9sences dans les r\u00e9seaux sociaux (Social Media)<\/h2>\n\n\n\n<p>Nous entretenons des pr\u00e9sences en ligne au sein de r\u00e9seaux sociaux et traitons dans ce cadre les donn\u00e9es des utilisateurs afin de communiquer avec les utilisateurs actifs sur ces r\u00e9seaux ou de proposer des informations nous concernant.<\/p>\n\n\n\n<p>Nous attirons votre attention sur le fait que les donn\u00e9es des utilisateurs peuvent \u00eatre trait\u00e9es en dehors de l'Union europ\u00e9enne. Il peut en r\u00e9sulter des risques pour les utilisateurs, par exemple parce qu'il pourrait \u00eatre plus difficile de faire valoir leurs droits.<\/p>\n\n\n\n<p>En outre, les donn\u00e9es des utilisateurs au sein des r\u00e9seaux sociaux sont g\u00e9n\u00e9ralement trait\u00e9es \u00e0 des fins d'\u00e9tudes de march\u00e9 et de publicit\u00e9. Ainsi, des profils d'utilisation peuvent \u00eatre cr\u00e9\u00e9s sur la base du comportement d'utilisation et des int\u00e9r\u00eats des utilisateurs qui en d\u00e9coulent. Les profils d'utilisation peuvent \u00e0 leur tour \u00eatre utilis\u00e9s, par exemple, pour diffuser des annonces publicitaires \u00e0 l'int\u00e9rieur et \u00e0 l'ext\u00e9rieur des r\u00e9seaux, qui sont suppos\u00e9es correspondre aux int\u00e9r\u00eats des utilisateurs. \u00c0 ces fins, des cookies sont g\u00e9n\u00e9ralement stock\u00e9s sur les ordinateurs des utilisateurs, dans lesquels le comportement d'utilisation et les int\u00e9r\u00eats des utilisateurs sont enregistr\u00e9s. En outre, des donn\u00e9es peuvent \u00eatre enregistr\u00e9es dans les profils d'utilisation ind\u00e9pendamment des appareils utilis\u00e9s par les utilisateurs (notamment lorsque les utilisateurs sont membres des plateformes concern\u00e9es et qu'ils sont connect\u00e9s \u00e0 celles-ci).<\/p>\n\n\n\n<p>Pour une pr\u00e9sentation d\u00e9taill\u00e9e des formes de traitement respectives et des possibilit\u00e9s d'opposition (opt-out), nous renvoyons aux d\u00e9clarations de protection des donn\u00e9es et aux indications des exploitants des r\u00e9seaux respectifs.<\/p>\n\n\n\n<p>Nous attirons \u00e9galement l'attention sur le fait que les demandes d'information et l'exercice des droits des personnes concern\u00e9es peuvent \u00eatre exerc\u00e9s le plus efficacement aupr\u00e8s des fournisseurs. Seuls les fournisseurs ont acc\u00e8s aux donn\u00e9es des utilisateurs et peuvent prendre directement les mesures appropri\u00e9es et fournir des informations. Si vous avez n\u00e9anmoins besoin d'aide, vous pouvez vous adresser \u00e0 nous.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'inventaire (p. ex. noms, adresses), donn\u00e9es de contact (p. ex. e-mail, num\u00e9ros de t\u00e9l\u00e9phone), donn\u00e9es de contenu (p. ex. saisies dans des formulaires en ligne), donn\u00e9es d'utilisation (p. ex. pages web visit\u00e9es, int\u00e9r\u00eat pour le contenu, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (p. ex. informations sur les appareils, adresses IP).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Utilisateurs (par exemple, visiteurs de sites web, utilisateurs de services en ligne).<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> Demandes de contact et communication, tracking (par ex. profilage bas\u00e9 sur les int\u00e9r\u00eats\/le comportement, utilisation de cookies), remarketing, mesure de la port\u00e9e (par ex. statistiques d'acc\u00e8s, reconnaissance des visiteurs r\u00e9currents).<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f. du RGPD).<\/li>\n<\/ul>\n\n\n\n<p><strong>Services utilis\u00e9s et fournisseurs de services :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Instagram : <\/strong>R\u00e9seau social, permet de partager des photos et des vid\u00e9os, de commenter et de mettre en favoris des publications, d'envoyer des messages, de s'abonner \u00e0 des profils et des pages ; <strong>Fournisseur de services :<\/strong> Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irlande ; <span class=\"prev_lb_wrp\"><strong>Bases juridiques :<\/strong> Int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f) du RGPD) ; <\/span><strong>Site web :<\/strong> <a href=\"https:\/\/www.instagram.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com<\/a>; <strong>D\u00e9claration de confidentialit\u00e9 :<\/strong> <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/privacycenter.instagram.com\/policy\/<\/a>; <strong>Base Transferts de pays tiers :<\/strong> Cadre de protection des donn\u00e9es (DPF).<\/li>\n\n\n\n<li><strong>Pages Facebook : <\/strong>Profils au sein du r\u00e9seau social Facebook - Nous sommes responsables, conjointement avec Meta Platforms Ireland Limited, de la collecte (mais pas du traitement ult\u00e9rieur) des donn\u00e9es des visiteurs de notre page Facebook (appel\u00e9e \u201epage fan\u201c). Ces donn\u00e9es comprennent des informations sur les types de contenu que les utilisateurs regardent ou avec lesquels ils interagissent, ou les actions qu'ils effectuent (voir la section \u201eChoses faites et fournies par vous et d'autres\u201c dans la politique de donn\u00e9es de Facebook : <a href=\"https:\/\/www.facebook.com\/privacy\/policy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/privacy\/policy\/<\/a>), ainsi que des informations sur les appareils utilis\u00e9s par les utilisateurs (par ex. adresses IP, syst\u00e8me d'exploitation, type de navigateur, param\u00e8tres de langue, donn\u00e9es de cookies ; voir la section \u201e Informations sur les appareils \u201c de la politique de confidentialit\u00e9 de Facebook : <a href=\"https:\/\/www.facebook.com\/privacy\/policy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/privacy\/policy\/<\/a>). Comme expliqu\u00e9 dans la politique de donn\u00e9es de Facebook sous \u201eComment utilisons-nous ces informations ?\u201c, Facebook collecte et utilise \u00e9galement des informations pour fournir des services d'analyse, appel\u00e9s \u201einsights de page\u201c, aux op\u00e9rateurs de pages afin de leur permettre de comprendre comment les personnes interagissent avec leurs pages et le contenu qui y est associ\u00e9. Nous avons conclu un accord sp\u00e9cifique avec Facebook (\u201eInformations sur les Pages-Insights\u201c), <a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a>), qui d\u00e9finit notamment les mesures de s\u00e9curit\u00e9 que Facebook doit respecter et dans lequel Facebook s'est d\u00e9clar\u00e9 pr\u00eat \u00e0 respecter les droits des personnes concern\u00e9es (c'est-\u00e0-dire que les utilisateurs peuvent, par exemple, adresser des demandes d'information ou de suppression directement \u00e0 Facebook). Les droits des utilisateurs (en particulier l'information, l'effacement, l'opposition et la plainte aupr\u00e8s de l'autorit\u00e9 de surveillance comp\u00e9tente) ne sont pas limit\u00e9s par les accords avec Facebook. Vous trouverez d'autres indications dans les \u201eInformations sur les Pages-Insights\u201c (<a href=\"https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data<\/a>). La responsabilit\u00e9 conjointe se limite \u00e0 la collecte et au transfert des donn\u00e9es \u00e0 Meta Platforms Ireland Limited, une soci\u00e9t\u00e9 \u00e9tablie dans l'UE. Le traitement ult\u00e9rieur des donn\u00e9es rel\u00e8ve de la seule responsabilit\u00e9 de Meta Platforms Ireland Limited, ce qui concerne notamment le transfert des donn\u00e9es \u00e0 la soci\u00e9t\u00e9 m\u00e8re Meta Platforms, Inc. aux \u00c9tats-Unis ; prestataire de services : Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/www.facebook.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/www.facebook.com\/privacy\/policy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/privacy\/policy\/<\/a>; Base des transferts vers des pays tiers : Data Privacy Framework (DPF).<\/li>\n\n\n\n<li><strong>LinkedIn : <\/strong>R\u00e9seau social - Nous sommes responsables, conjointement avec LinkedIn Irland Unlimited Company, de la collecte (mais pas du traitement ult\u00e9rieur) des donn\u00e9es des visiteurs aux fins de l'\u00e9tablissement des \u201ePage-Insights\u201c (statistiques) de nos profils LinkedIn.<br>Ces donn\u00e9es comprennent des informations sur les types de contenu que les utilisateurs consultent ou avec lesquels ils interagissent, ou sur les actions qu'ils effectuent, ainsi que des informations sur les appareils utilis\u00e9s par les utilisateurs (par exemple, adresses IP, syst\u00e8me d'exploitation, type de navigateur, param\u00e8tres linguistiques, donn\u00e9es de cookies) et des informations issues du profil des utilisateurs, telles que la fonction professionnelle, le pays, le secteur, le niveau hi\u00e9rarchique, la taille de l'entreprise et le statut d'emploi. Les informations relatives \u00e0 la protection des donn\u00e9es concernant le traitement des donn\u00e9es des utilisateurs par LinkedIn peuvent \u00eatre consult\u00e9es dans la d\u00e9claration de confidentialit\u00e9 de LinkedIn : <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a>. Nous avons conclu un accord sp\u00e9cifique avec LinkedIn Irlande (\u201eAddendum au contr\u00f4leur commun de Page Insights (l\u201a\u2018Addendum\u201c)\", <a href=\"https:\/\/legal.linkedin.com\/pages-joint-controller-addendum\" target=\"_blank\" rel=\"noopener\">https:\/\/legal.linkedin.com\/pages-joint-controller-addendum<\/a>), dans lequel sont notamment r\u00e9gl\u00e9es les mesures de s\u00e9curit\u00e9 que LinkedIn doit respecter et dans lequel LinkedIn s'est d\u00e9clar\u00e9 pr\u00eat \u00e0 respecter les droits des personnes concern\u00e9es (c'est-\u00e0-dire que les utilisateurs peuvent par exemple adresser directement \u00e0 LinkedIn des demandes de renseignements ou de suppression). Les droits des utilisateurs (notamment l'acc\u00e8s, l'effacement, l'opposition et le recours aupr\u00e8s de l'autorit\u00e9 de contr\u00f4le comp\u00e9tente) ne sont pas limit\u00e9s par les accords conclus avec LinkedIn. La responsabilit\u00e9 conjointe se limite \u00e0 la collecte des donn\u00e9es par Ireland Unlimited Company, une entreprise bas\u00e9e dans l'UE, et \u00e0 leur transmission \u00e0 cette derni\u00e8re. Le traitement ult\u00e9rieur des donn\u00e9es incombe exclusivement \u00e0 Ireland Unlimited Company, ce qui concerne notamment le transfert des donn\u00e9es \u00e0 la soci\u00e9t\u00e9 m\u00e8re LinkedIn Corporation aux \u00c9tats-Unis ; fournisseur de services : LinkedIn Ireland Unlimited Company, Wilton Place, Dublin 2, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/www.linkedin.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a>; base des transferts vers des pays tiers : Data Privacy Framework (DPF) ; possibilit\u00e9 d'opposition (opt-out) : <a href=\"https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out<\/a>.<\/li>\n\n\n\n<li><strong>Pinterest : <\/strong>R\u00e9seau social ; fournisseur de services : Pinterest Inc., 635 High Street, Palo Alto, CA, 94301, \u00c9tats-Unis ; site web : <a href=\"https:\/\/www.pinterest.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.pinterest.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/about.pinterest.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/about.pinterest.com\/de\/privacy-policy<\/a>; Informations compl\u00e9mentaires : Pinterest Annexe relative \u00e0 l'\u00e9change de donn\u00e9es (ANNEXE A) : <a href=\"https:\/\/business.pinterest.com\/de\/pinterest-advertising-services-agreement\/\" target=\"_blank\" rel=\"noopener\">https:\/\/business.pinterest.com\/de\/pinterest-advertising-services-agreement\/<\/a>.<\/li>\n\n\n\n<li><strong>TikTok : <\/strong>R\u00e9seau social \/ plateforme vid\u00e9o ; fournisseur de services : musical.ly Inc, 10351 Santa Monica Blvd #310, Los Angeles, CA 90025 USA ; site web : <a href=\"https:\/\/www.tiktok.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.tiktok.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/www.tiktok.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.tiktok.com\/de\/privacy-policy<\/a>.<\/li>\n\n\n\n<li><strong>X : <\/strong>R\u00e9seau social ; fournisseur de services : Twitter International Company, One Cumberland Place, Fenian Street, Dublin 2 D02 AX07, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/x.com\" target=\"_blank\" rel=\"noopener\">https:\/\/x.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/x.com\/de\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/x.com\/de\/privacy<\/a>.<\/li>\n\n\n\n<li><strong>YouTube : <\/strong>R\u00e9seau social et plateforme vid\u00e9o ; fournisseur de services : Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande, soci\u00e9t\u00e9 m\u00e8re : Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, \u00c9tats-Unis ; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>; possibilit\u00e9 d'opposition (opt-out) : <a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener\">https:\/\/adssettings.google.com\/authenticated<\/a>; Base du transfert vers un pays tiers : Data Privacy Framework.<\/li>\n\n\n\n<li><strong>Xing : <\/strong>R\u00e9seau social ; Fournisseur de services : XING AG, Dammtorstra\u00dfe 29-32, 20354 Hambourg, Allemagne ; Site web : <a href=\"https:\/\/www.xing.de\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.xing.de<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/privacy.xing.com\/de\/datenschutzerklaerung\" target=\"_blank\" rel=\"noopener\">https:\/\/privacy.xing.com\/de\/datenschutzerklaerung<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m328\">Plugins et fonctions int\u00e9gr\u00e9es et contenus<\/h2>\n\n\n\n<p>Nous int\u00e9grons dans notre offre en ligne des \u00e9l\u00e9ments fonctionnels et de contenu qui sont obtenus \u00e0 partir des serveurs de leurs fournisseurs respectifs (ci-apr\u00e8s d\u00e9nomm\u00e9s \u201efournisseurs tiers\u201d). Il peut s'agir par exemple de graphiques, de vid\u00e9os ou de boutons de m\u00e9dias sociaux ainsi que de contributions (d\u00e9sign\u00e9s ci-apr\u00e8s par le terme g\u00e9n\u00e9rique de \u201econtenus\u201d).<\/p>\n\n\n\n<p>L'int\u00e9gration suppose toujours que les fournisseurs tiers de ces contenus traitent l'adresse IP des utilisateurs, car sans cette adresse IP, ils ne pourraient pas envoyer les contenus \u00e0 leur navigateur. L'adresse IP est donc n\u00e9cessaire pour la pr\u00e9sentation de ces contenus ou fonctions. Nous nous effor\u00e7ons de n'utiliser que des contenus dont les fournisseurs respectifs utilisent l'adresse IP uniquement pour la livraison des contenus. Les fournisseurs tiers peuvent en outre utiliser des \u201epixel tags\u201c (graphiques invisibles, \u00e9galement appel\u00e9s \u201ebalises web\u201c) \u00e0 des fins statistiques ou de marketing. Les \"pixel tags\" permettent d'\u00e9valuer des informations telles que le trafic de visiteurs sur les pages de ce site web. Les informations pseudonymes peuvent en outre \u00eatre enregistr\u00e9es dans des cookies sur l'appareil de l'utilisateur et contenir, entre autres, des informations techniques sur le navigateur et le syst\u00e8me d'exploitation, sur les pages web de r\u00e9f\u00e9rence, sur l'heure de la visite ainsi que d'autres indications sur l'utilisation de notre offre en ligne, mais aussi \u00eatre li\u00e9es \u00e0 de telles informations provenant d'autres sources.<\/p>\n\n\n\n<p><strong>Remarques sur les bases juridiques :<\/strong> Dans la mesure o\u00f9 nous demandons aux utilisateurs de consentir \u00e0 l'utilisation des fournisseurs tiers, la base juridique du traitement des donn\u00e9es est le consentement. Dans le cas contraire, les donn\u00e9es des utilisateurs sont trait\u00e9es sur la base de nos int\u00e9r\u00eats l\u00e9gitimes (c'est-\u00e0-dire l'int\u00e9r\u00eat \u00e0 fournir des services efficaces, \u00e9conomiques et adapt\u00e9s aux besoins des destinataires). Dans ce contexte, nous souhaitons \u00e9galement attirer votre attention sur les informations relatives \u00e0 l'utilisation des cookies dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Types de donn\u00e9es trait\u00e9es :<\/strong> Donn\u00e9es d'utilisation (p. ex. pages web visit\u00e9es, int\u00e9r\u00eat pour les contenus, temps d'acc\u00e8s), m\u00e9tadonn\u00e9es\/donn\u00e9es de communication (p. ex. informations sur les appareils, adresses IP), donn\u00e9es de localisation (indications sur la position g\u00e9ographique d'un appareil ou d'une personne), donn\u00e9es de contenu (p. ex. saisies dans des formulaires en ligne), donn\u00e9es de base (p. ex. noms, adresses), donn\u00e9es de contact (p. ex. e-mail, num\u00e9ros de t\u00e9l\u00e9phone).<\/li>\n\n\n\n<li><strong>Personnes concern\u00e9es :<\/strong> Utilisateurs (par exemple, visiteurs de sites web, utilisateurs de services en ligne), partenaires de communication.<\/li>\n\n\n\n<li><strong>les finalit\u00e9s du traitement :<\/strong> Mise \u00e0 disposition de notre offre en ligne et convivialit\u00e9, fourniture de prestations contractuelles et service client, demandes de contact et communication, suivi (par ex. profilage bas\u00e9 sur les int\u00e9r\u00eats\/le comportement, utilisation de cookies), marketing bas\u00e9 sur les int\u00e9r\u00eats et le comportement, profilage (cr\u00e9ation de profils d'utilisateurs), mesures de s\u00e9curit\u00e9, gestion et r\u00e9ponse aux demandes.<\/li>\n\n\n\n<li><strong>Bases juridiques :<\/strong> Int\u00e9r\u00eats l\u00e9gitimes (art. 6, paragraphe 1, phrase 1, point f. RGPD), consentement (art. 6, paragraphe 1, phrase 1, point a. RGPD), ex\u00e9cution du contrat et demandes pr\u00e9contractuelles (art. 6, paragraphe 1, phrase 1, point b. RGPD).<\/li>\n<\/ul>\n\n\n\n<p><strong>Services utilis\u00e9s et fournisseurs de services :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list m-elements\">\n<li><strong>Google Fonts (obtenu \u00e0 partir du serveur de Google) : <\/strong>Obtention de polices (et de symboles) dans le but d'une utilisation techniquement s\u00fbre, sans entretien et efficace des polices et des symboles en ce qui concerne l'actualit\u00e9 et les temps de chargement, leur pr\u00e9sentation uniforme et la prise en compte d'\u00e9ventuelles restrictions en mati\u00e8re de droit de licence. L'adresse IP de l'utilisateur est communiqu\u00e9e au fournisseur des polices afin que les polices puissent \u00eatre mises \u00e0 disposition dans le navigateur de l'utilisateur. En outre, des donn\u00e9es techniques (param\u00e8tres linguistiques, r\u00e9solution d'\u00e9cran, syst\u00e8me d'exploitation, mat\u00e9riel utilis\u00e9) n\u00e9cessaires \u00e0 la mise \u00e0 disposition des polices en fonction des appareils utilis\u00e9s et de l'environnement technique sont transmises. Ces donn\u00e9es peuvent \u00eatre trait\u00e9es sur un serveur du fournisseur des polices aux \u00c9tats-Unis - Lors de la visite de notre offre en ligne, les navigateurs des utilisateurs envoient leurs requ\u00eates HTTP \u00e0 l'API Web de Google Fonts (c'est-\u00e0-dire une interface logicielle pour la r\u00e9cup\u00e9ration des polices). L'API Web de Google Fonts met \u00e0 la disposition des utilisateurs les feuilles de style en cascade (CSS) de Google Fonts et ensuite les polices sp\u00e9cifi\u00e9es dans le CCS. Ces requ\u00eates HTTP comprennent (1) l'adresse IP utilis\u00e9e par l'utilisateur concern\u00e9 pour acc\u00e9der \u00e0 Internet, (2) l'URL demand\u00e9e sur le serveur Google et (3) les en-t\u00eates HTTP, y compris l'agent utilisateur d\u00e9crivant les versions du navigateur et du syst\u00e8me d'exploitation des visiteurs du site, ainsi que l'URL de r\u00e9f\u00e9rence (c'est-\u00e0-dire la page Web sur laquelle la police Google doit \u00eatre affich\u00e9e). Les adresses IP ne sont ni enregistr\u00e9es ni stock\u00e9es sur les serveurs de Google et elles ne sont pas analys\u00e9es. L'API Web de Google Fonts enregistre les d\u00e9tails des requ\u00eates HTTP (URL demand\u00e9e, agent utilisateur et URL de r\u00e9f\u00e9rence). L'acc\u00e8s \u00e0 ces donn\u00e9es est limit\u00e9 et strictement contr\u00f4l\u00e9. L'URL demand\u00e9e identifie les familles de polices pour lesquelles l'utilisateur souhaite charger des polices. Ces donn\u00e9es sont consign\u00e9es afin que Google puisse d\u00e9terminer la fr\u00e9quence \u00e0 laquelle une famille de polices donn\u00e9e est demand\u00e9e. Avec l'API Google Fonts Web, l'agent utilisateur doit adapter la police qui est g\u00e9n\u00e9r\u00e9e pour le type de navigateur concern\u00e9. L'agent utilisateur est principalement consign\u00e9 \u00e0 des fins de d\u00e9bogage et utilis\u00e9 pour g\u00e9n\u00e9rer des statistiques d'utilisation agr\u00e9g\u00e9es qui permettent de mesurer la popularit\u00e9 des familles de polices. Ces statistiques d'utilisation agr\u00e9g\u00e9es sont publi\u00e9es sur la page \u201eAnalyses\u201c de Google Fonts. Enfin, l'URL de r\u00e9f\u00e9rence est consign\u00e9e, ce qui permet d'utiliser les donn\u00e9es pour la maintenance de la production et de g\u00e9n\u00e9rer un rapport agr\u00e9g\u00e9 sur les meilleures int\u00e9grations en fonction du nombre de demandes de polices. Selon ses propres informations, Google n'utilise pas les informations collect\u00e9es par Google Fonts pour cr\u00e9er des profils d'utilisateurs finaux ou pour diffuser des annonces cibl\u00e9es ; fournisseur de services : Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, phrase 1, point f) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/fonts.google.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/fonts.google.com\/<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>; Base des transferts vers des pays tiers : Data Privacy Framework (DPF) ; Informations compl\u00e9mentaires : <a href=\"https:\/\/developers.google.com\/fonts\/faq\/privacy?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/developers.google.com\/fonts\/faq\/privacy?hl=de<\/a>.<\/li>\n\n\n\n<li><strong>Google Maps : <\/strong>Nous int\u00e9grons les cartes g\u00e9ographiques du service \u201eGoogle Maps\u201c du fournisseur Google. Les donn\u00e9es trait\u00e9es peuvent notamment inclure les adresses IP et les donn\u00e9es de localisation des utilisateurs ; <strong>Fournisseur de services :<\/strong> Google Cloud EMEA Limited, 70 Sir John Rogerson's Quay, Dublin 2, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : consentement (article 6, paragraphe 1, phrase 1, point a) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/mapsplatform.google.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/mapsplatform.google.com\/<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>; Base des transferts vers des pays tiers : Data Privacy Framework (DPF).<\/li>\n\n\n\n<li><strong>Vid\u00e9os sur YouTube : <\/strong>Contenu vid\u00e9o ; fournisseur de services : Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande ; <span class=\"prev_lb_wrp\">Bases juridiques : consentement (article 6, paragraphe 1, phrase 1, point a) du RGPD) ; <\/span>Site web : <a href=\"https:\/\/www.youtube.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youtube.com<\/a>; D\u00e9claration de confidentialit\u00e9 : <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>; base des transferts vers des pays tiers : Data Privacy Framework (DPF) ; possibilit\u00e9 d'opposition (opt-out) : Plugin d'opt-out : <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>, param\u00e8tres d'affichage des publicit\u00e9s : <a href=\"https:\/\/myadcenter.google.com\/personalizationoff\" target=\"_blank\" rel=\"noopener\">https:\/\/myadcenter.google.com\/personalizationoff<\/a>.<\/li>\n\n\n\n<li><strong>Utilisation d'un chatbot d'intelligence artificielle (Google Gemini via Vertex AI)<\/strong><br>Nous utilisons un chatbot pilot\u00e9 par l'IA sur notre site web afin de r\u00e9pondre de mani\u00e8re automatis\u00e9e aux demandes des utilisateurs et d'am\u00e9liorer notre service client.\n<ul class=\"wp-block-list\">\n<li><span style=\"text-decoration: underline;\">Nature et \u00e9tendue du traitement<br><\/span>Lors de l'utilisation du chatbot, les textes que vous saisissez dans la fen\u00eatre de chat (inputs) ainsi que les m\u00e9tadonn\u00e9es techniquement n\u00e9cessaires (par ex. adresse IP) sont transmis \u00e0 la plateforme Google Cloud. Nous utilisons pour cela le service Google Cloud Vertex AI (mod\u00e8le : Gemini 3 Flash). Le traitement des donn\u00e9es s'effectue sur les serveurs de Google. Selon les conditions d'utilisation de Google Vertex AI, les donn\u00e9es saisies ne sont pas utilis\u00e9es pour entra\u00eener les mod\u00e8les d'IA de Google pour d'autres clients.<\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\">Finalit\u00e9 du traitement des donn\u00e9es<br><\/span>La finalit\u00e9 du traitement est de r\u00e9pondre de mani\u00e8re interactive aux demandes des utilisateurs et d'am\u00e9liorer l'efficacit\u00e9 de notre support.<\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\">Base juridique<\/span><br>Le traitement est effectu\u00e9 sur la base de notre int\u00e9r\u00eat l\u00e9gitime \u00e0 une communication moderne, rapide et interactive avec les visiteurs de notre site web, conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point f du RGPD.<\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\">Dur\u00e9e de stockage<\/span><br>Les historiques de chat sont stock\u00e9s localement dans notre base de donn\u00e9es afin de garantir la qualit\u00e9 du service. Nous effa\u00e7ons ces donn\u00e9es de mani\u00e8re automatis\u00e9e selon un principe de roulement (enregistrement des 10 000 derni\u00e8res entr\u00e9es). Nous n'effectuons pas de stockage au-del\u00e0 de cette dur\u00e9e, sauf si des obligations l\u00e9gales de conservation s'y opposent.<\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\">Destinataire \/ Transfert de pays tiers<br><\/span>Le destinataire des donn\u00e9es est Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande. Dans ce cadre, il peut y avoir un transfert de donn\u00e9es vers la soci\u00e9t\u00e9 m\u00e8re Google LLC aux \u00c9tats-Unis. Google est certifi\u00e9 selon le cadre de protection des donn\u00e9es UE-U.S., ce qui garantit un niveau de protection des donn\u00e9es ad\u00e9quat. <\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\">Droit d'opposition<\/span><br>Vous pouvez mettre fin \u00e0 l'utilisation du chatbot \u00e0 tout moment en fermant la fen\u00eatre de chat. Aucune autre transmission de donn\u00e9es n'a alors lieu.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m12\">Suppression des donn\u00e9es<\/h2>\n\n\n\n<p>Les donn\u00e9es que nous traitons sont supprim\u00e9es conform\u00e9ment aux dispositions l\u00e9gales d\u00e8s que les consentements autoris\u00e9s pour leur traitement sont r\u00e9voqu\u00e9s ou que d'autres autorisations ne sont plus valables (par exemple, lorsque la finalit\u00e9 du traitement de ces donn\u00e9es a disparu ou qu'elles ne sont plus n\u00e9cessaires \u00e0 cette fin).<\/p>\n\n\n\n<p>Si les donn\u00e9es ne sont pas supprim\u00e9es parce qu'elles sont n\u00e9cessaires \u00e0 d'autres fins autoris\u00e9es par la loi, leur traitement sera limit\u00e9 \u00e0 ces fins. En d'autres termes, les donn\u00e9es sont bloqu\u00e9es et ne sont pas trait\u00e9es \u00e0 d'autres fins. Cela s'applique par exemple aux donn\u00e9es qui doivent \u00eatre conserv\u00e9es pour des raisons commerciales ou fiscales ou dont le stockage est n\u00e9cessaire pour faire valoir, exercer ou d\u00e9fendre des droits juridiques ou pour prot\u00e9ger les droits d'une autre personne physique ou morale.<\/p>\n\n\n\n<p>D'autres indications sur la suppression des donn\u00e9es \u00e0 caract\u00e8re personnel peuvent en outre \u00eatre fournies dans le cadre des diff\u00e9rentes indications sur la protection des donn\u00e9es de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m15\">Modification et mise \u00e0 jour de la d\u00e9claration de confidentialit\u00e9<\/h2>\n\n\n\n<p>Nous vous prions de vous informer r\u00e9guli\u00e8rement sur le contenu de notre d\u00e9claration de protection des donn\u00e9es. Nous adaptons la d\u00e9claration de protection des donn\u00e9es d\u00e8s que les modifications des traitements de donn\u00e9es que nous effectuons le rendent n\u00e9cessaire. Nous vous informons d\u00e8s que les modifications rendent n\u00e9cessaire une action de coop\u00e9ration de votre part (par ex. consentement) ou toute autre notification individuelle.<\/p>\n\n\n\n<p>Dans la mesure o\u00f9 nous indiquons dans cette d\u00e9claration de protection des donn\u00e9es les adresses et les coordonn\u00e9es d'entreprises et d'organisations, nous vous prions de noter que les adresses peuvent changer au fil du temps et nous vous prions de v\u00e9rifier les donn\u00e9es avant de nous contacter.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m10\">Droits des personnes concern\u00e9es<\/h2>\n\n\n\n<p>En tant que personne concern\u00e9e, vous disposez de diff\u00e9rents droits en vertu du RGPD, qui d\u00e9coulent notamment des articles 15 \u00e0 21 du RGPD :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Droit d'opposition :<\/strong> Vous avez le droit de vous opposer \u00e0 tout moment, pour des raisons tenant \u00e0 votre situation particuli\u00e8re, \u00e0 un traitement des donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant effectu\u00e9 sur la base de l'article 6, paragraphe 1, point e) ou f), du RGPD ; cela s'applique \u00e9galement \u00e0 un profilage fond\u00e9 sur ces dispositions. Si les donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant sont trait\u00e9es \u00e0 des fins de publicit\u00e9 directe, vous avez le droit de vous opposer \u00e0 tout moment au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant \u00e0 de telles fins de publicit\u00e9 ; cela vaut \u00e9galement pour le profilage dans la mesure o\u00f9 il est li\u00e9 \u00e0 une telle publicit\u00e9 directe.<\/li>\n\n\n\n<li><strong>Droit de r\u00e9tractation pour les consentements :<\/strong> Vous avez le droit de r\u00e9voquer \u00e0 tout moment les autorisations accord\u00e9es.<\/li>\n\n\n\n<li><strong>Droit d'acc\u00e8s :<\/strong> Vous avez le droit d'obtenir la confirmation que les donn\u00e9es concern\u00e9es sont ou ne sont pas trait\u00e9es et d'acc\u00e9der \u00e0 ces donn\u00e9es, ainsi que d'obtenir des informations suppl\u00e9mentaires et une copie des donn\u00e9es conform\u00e9ment aux exigences l\u00e9gales.<\/li>\n\n\n\n<li><strong>Droit de rectification :<\/strong> Conform\u00e9ment aux dispositions l\u00e9gales, vous avez le droit d'exiger que les donn\u00e9es vous concernant soient compl\u00e9t\u00e9es ou que les donn\u00e9es inexactes vous concernant soient rectifi\u00e9es.<\/li>\n\n\n\n<li><strong>Droit \u00e0 l'effacement et \u00e0 la limitation du traitement :<\/strong> Conform\u00e9ment aux dispositions l\u00e9gales, vous avez le droit d'exiger que les donn\u00e9es vous concernant soient imm\u00e9diatement effac\u00e9es ou, \u00e0 d\u00e9faut, de demander une limitation du traitement des donn\u00e9es conform\u00e9ment aux dispositions l\u00e9gales.<\/li>\n\n\n\n<li><strong>Droit \u00e0 la portabilit\u00e9 des donn\u00e9es :<\/strong> Vous avez le droit de recevoir les donn\u00e9es vous concernant que vous nous avez fournies dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine, conform\u00e9ment aux exigences l\u00e9gales, ou de demander leur transmission \u00e0 un autre responsable.<\/li>\n\n\n\n<li><strong>Plainte aupr\u00e8s de l'autorit\u00e9 de surveillance :<\/strong> Vous avez \u00e9galement le droit, conform\u00e9ment aux dispositions l\u00e9gales, d'introduire une r\u00e9clamation aupr\u00e8s d'une autorit\u00e9 de contr\u00f4le, notamment dans l'\u00c9tat membre de votre r\u00e9sidence habituelle, de votre lieu de travail ou du lieu de l'infraction pr\u00e9sum\u00e9e, si vous estimez que le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant enfreint le RGPD.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m42\">D\u00e9finitions des termes<\/h2>\n\n\n\n<p>Dans cette section, vous trouverez un aper\u00e7u des termes utilis\u00e9s dans cette d\u00e9claration de protection des donn\u00e9es. De nombreux termes sont tir\u00e9s de la loi et d\u00e9finis principalement \u00e0 l'article 4 du RGPD. Les d\u00e9finitions l\u00e9gales sont contraignantes. En revanche, les explications suivantes doivent avant tout servir \u00e0 la compr\u00e9hension. Les termes sont class\u00e9s par ordre alphab\u00e9tique.<\/p>\n\n\n\n<ul class=\"wp-block-list glossary\">\n<li><strong>\u00c9valuation de l'action de visite :<\/strong> \u201eL\u201c\u201e\u00e9valuation des actions de visite\u201c (en anglais \"Conversion Tracking\") d\u00e9signe une proc\u00e9dure permettant de d\u00e9terminer l'efficacit\u00e9 des mesures de marketing. Pour ce faire, un cookie est g\u00e9n\u00e9ralement enregistr\u00e9 sur l'appareil de l'utilisateur au sein des pages web sur lesquelles les mesures de marketing sont prises, puis il est \u00e0 nouveau consult\u00e9 sur la page web cible. Par exemple, cela nous permet de savoir si les annonces que nous avons plac\u00e9es sur d'autres sites web ont \u00e9t\u00e9 efficaces).<\/li>\n\n\n\n<li><strong>Renseignements sur la solvabilit\u00e9 :<\/strong> Les d\u00e9cisions automatis\u00e9es reposent sur un traitement automatique des donn\u00e9es sans intervention humaine (par exemple, en cas de refus automatique d'un achat sur facture, d'une demande de cr\u00e9dit en ligne ou d'une proc\u00e9dure de candidature en ligne sans aucune intervention humaine). De telles d\u00e9cisions automatis\u00e9es ne sont autoris\u00e9es par l'article 22 du RGPD que si les personnes concern\u00e9es y consentent, si elles sont n\u00e9cessaires \u00e0 l'ex\u00e9cution d'un contrat ou si la l\u00e9gislation nationale autorise de telles d\u00e9cisions.<\/li>\n\n\n\n<li><strong>Suivi cross-device :<\/strong> Le cross-device tracking est une forme de tracking dans le cadre de laquelle les informations sur le comportement et les int\u00e9r\u00eats des utilisateurs sont saisies sur tous les appareils dans ce que l'on appelle des profils, en attribuant aux utilisateurs un identifiant en ligne. Ainsi, les informations sur les utilisateurs peuvent \u00eatre analys\u00e9es \u00e0 des fins de marketing, ind\u00e9pendamment du navigateur ou de l'appareil utilis\u00e9 (par ex. t\u00e9l\u00e9phone portable ou ordinateur de bureau). Chez la plupart des fournisseurs, l'identifiant en ligne n'est pas associ\u00e9 \u00e0 des donn\u00e9es claires telles que le nom, l'adresse postale ou l'adresse \u00e9lectronique.<\/li>\n\n\n\n<li><strong>Masquage IP :<\/strong> Le \u201emasquage IP\u201d est une m\u00e9thode qui consiste \u00e0 supprimer le dernier octet, c'est-\u00e0-dire les deux derniers chiffres d'une adresse IP, afin que l'adresse IP ne puisse plus servir \u00e0 identifier une personne de mani\u00e8re univoque. Le masquage IP est donc un moyen de pseudonymiser les proc\u00e9dures de traitement, notamment dans le marketing en ligne.<\/li>\n\n\n\n<li><strong>Marketing bas\u00e9 sur les int\u00e9r\u00eats et le comportement :<\/strong> On parle de marketing bas\u00e9 sur les int\u00e9r\u00eats et\/ou le comportement lorsque les int\u00e9r\u00eats potentiels des utilisateurs pour les annonces et autres contenus sont pr\u00e9d\u00e9termin\u00e9s le plus pr\u00e9cis\u00e9ment possible. Cela se fait \u00e0 l'aide d'informations sur leur comportement ant\u00e9rieur (par ex. visite et s\u00e9jour sur certaines pages web, comportement d'achat ou interaction avec d'autres utilisateurs), qui sont enregistr\u00e9es dans un profil. En r\u00e8gle g\u00e9n\u00e9rale, des cookies sont utilis\u00e9s \u00e0 ces fins.<\/li>\n\n\n\n<li><strong>Mesure de la conversion :<\/strong> La mesure de la conversion est une m\u00e9thode qui permet de d\u00e9terminer l'efficacit\u00e9 des mesures marketing. Pour ce faire, un cookie est g\u00e9n\u00e9ralement enregistr\u00e9 sur l'appareil de l'utilisateur au sein des pages web sur lesquelles les mesures de marketing sont prises, puis il est \u00e0 nouveau consult\u00e9 sur la page web cible. Cela nous permet par exemple de savoir si les annonces que nous avons plac\u00e9es sur d'autres sites web ont \u00e9t\u00e9 efficaces.<\/li>\n\n\n\n<li><strong>Donn\u00e9es personnelles :<\/strong> \u201edonn\u00e9es \u00e0 caract\u00e8re personnel\u201c : toute information se rapportant \u00e0 une personne physique identifi\u00e9e ou identifiable (ci-apr\u00e8s d\u00e9nomm\u00e9e \u201epersonne concern\u00e9e\u201c) ; est r\u00e9put\u00e9e identifiable une personne physique qui peut \u00eatre identifi\u00e9e, directement ou indirectement, notamment par r\u00e9f\u00e9rence \u00e0 un identifiant, tel qu'un nom, \u00e0 un num\u00e9ro d'identification, \u00e0 des donn\u00e9es de localisation, \u00e0 un identifiant en ligne (par exemple un cookie) ou \u00e0 une ou plusieurs caract\u00e9ristiques particuli\u00e8res, propres \u00e0 l'identit\u00e9 physique, physiologique, g\u00e9n\u00e9tique, psychique, \u00e9conomique, culturelle ou sociale de cette personne physique.<\/li>\n\n\n\n<li><strong>Profilage :<\/strong> On entend par \u201eprofilage\u201c tout type de traitement automatis\u00e9 de donn\u00e9es \u00e0 caract\u00e8re personnel consistant \u00e0 utiliser ces donn\u00e9es \u00e0 caract\u00e8re personnel pour analyser, \u00e9valuer ou pr\u00e9dire certains aspects personnels relatifs \u00e0 une personne physique (selon le type de profilage, il peut s'agir d'informations concernant l'\u00e2ge, le sexe, les donn\u00e9es de localisation et de mouvement, l'interaction avec des sites web et leur contenu, les habitudes d'achat, les interactions sociales avec d'autres personnes) (par exemple, les int\u00e9r\u00eats pour certains contenus ou produits, les habitudes de clics sur un site web ou la localisation). Les cookies et les balises web sont souvent utilis\u00e9s \u00e0 des fins de profilage.<\/li>\n\n\n\n<li><strong>Mesure de la port\u00e9e :<\/strong> La mesure d'audience (\u00e9galement appel\u00e9e Web Analytics) sert \u00e0 \u00e9valuer le flux de visiteurs d'une offre en ligne et peut inclure le comportement ou l'int\u00e9r\u00eat des visiteurs pour certaines informations, comme le contenu des pages web. Gr\u00e2ce \u00e0 l'analyse de la port\u00e9e, les propri\u00e9taires de sites web peuvent par exemple savoir \u00e0 quelle heure les visiteurs visitent leur site web et quels sont les contenus qui les int\u00e9ressent. Cela leur permet par exemple de mieux adapter le contenu du site web aux besoins de leurs visiteurs. \u00c0 des fins d'analyse de la port\u00e9e, des cookies et des balises web pseudonymes sont souvent utilis\u00e9s pour reconna\u00eetre les visiteurs r\u00e9currents et obtenir ainsi des analyses plus pr\u00e9cises sur l'utilisation d'une offre en ligne.<\/li>\n\n\n\n<li><strong>Le remarketing :<\/strong> On parle de \u201eremarketing\u201c ou de \u201eretargeting\u201c lorsque, par exemple, on note \u00e0 des fins publicitaires les produits auxquels un utilisateur s'est int\u00e9ress\u00e9 sur un site web, afin de rappeler ces produits \u00e0 l'utilisateur sur d'autres sites web, par exemple dans des annonces publicitaires.<\/li>\n\n\n\n<li><strong>donn\u00e9es de localisation :<\/strong> Les donn\u00e9es de localisation sont g\u00e9n\u00e9r\u00e9es lorsqu'un appareil mobile (ou un autre appareil disposant des conditions techniques de localisation) se connecte \u00e0 une cellule radio, \u00e0 un r\u00e9seau local sans fil ou \u00e0 d'autres moyens techniques et fonctions de localisation similaires. Les donn\u00e9es de localisation servent \u00e0 indiquer \u00e0 quelle position g\u00e9ographique d\u00e9terminable du globe se trouve l'appareil concern\u00e9. Les donn\u00e9es de localisation peuvent \u00eatre utilis\u00e9es, par exemple, pour afficher des fonctions cartographiques ou d'autres informations d\u00e9pendant d'un lieu.<\/li>\n\n\n\n<li><strong>Suivi :<\/strong> On parle de \u201etracking\u201c lorsqu'il est possible de suivre le comportement des utilisateurs sur plusieurs offres en ligne. En r\u00e8gle g\u00e9n\u00e9rale, des informations sur le comportement et les int\u00e9r\u00eats sont enregistr\u00e9es dans des cookies ou sur les serveurs des fournisseurs de technologies de suivi (profilage) en ce qui concerne les offres en ligne utilis\u00e9es. Ces informations peuvent ensuite \u00eatre utilis\u00e9es, par exemple, pour afficher aux utilisateurs des publicit\u00e9s qui correspondent vraisemblablement \u00e0 leurs int\u00e9r\u00eats.<\/li>\n\n\n\n<li><strong>Responsable :<\/strong> Le terme \u201eresponsable\u201c d\u00e9signe la personne physique ou morale, l'autorit\u00e9 publique, le service ou tout autre organisme qui, seul ou conjointement avec d'autres, d\u00e9termine les finalit\u00e9s et les moyens du traitement de donn\u00e9es \u00e0 caract\u00e8re personnel.<\/li>\n\n\n\n<li><strong>traitement :<\/strong> \u201etraitement\u201c : toute op\u00e9ration ou tout ensemble d'op\u00e9rations effectu\u00e9es ou non \u00e0 l'aide de proc\u00e9d\u00e9s automatis\u00e9s et appliqu\u00e9es \u00e0 des donn\u00e9es \u00e0 caract\u00e8re personnel. Le terme est large et couvre pratiquement toute manipulation de donn\u00e9es, qu'il s'agisse de la collecte, de l'analyse, de l'enregistrement, de la transmission ou de l'effacement.<\/li>\n\n\n\n<li><strong>Formation de groupes cibles :<\/strong> On parle de ciblage (ou \u201eCustom Audiences\u201c) lorsque des groupes cibles sont d\u00e9termin\u00e9s \u00e0 des fins publicitaires, par exemple pour l'insertion d'annonces publicitaires. Par exemple, l'int\u00e9r\u00eat d'un utilisateur pour certains produits ou th\u00e8mes sur Internet permet de d\u00e9duire que cet utilisateur est int\u00e9ress\u00e9 par des annonces publicitaires pour des produits similaires ou par la boutique en ligne dans laquelle il a consult\u00e9 les produits. On parle \u00e0 nouveau de \u201eLookalike Audiences\u201c (ou de groupes cibles similaires) lorsque les contenus jug\u00e9s appropri\u00e9s sont affich\u00e9s \u00e0 des utilisateurs dont les profils ou les int\u00e9r\u00eats sont suppos\u00e9s correspondre \u00e0 ceux des utilisateurs pour lesquels les profils ont \u00e9t\u00e9 cr\u00e9\u00e9s. En r\u00e8gle g\u00e9n\u00e9rale, des cookies et des balises web sont utilis\u00e9s pour la cr\u00e9ation d'audiences personnalis\u00e9es et d'audiences similaires.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Einleitung Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als &#8222;Daten\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns durchgef\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":148,"footnotes":""},"class_list":["post-1527","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/pages\/1527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/comments?post=1527"}],"version-history":[{"count":0,"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/pages\/1527\/revisions"}],"wp:attachment":[{"href":"https:\/\/vanfittery.de\/fr\/wp-json\/wp\/v2\/media?parent=1527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}